{"id":119867,"date":"2024-01-09T09:34:47","date_gmt":"2024-01-09T08:34:47","guid":{"rendered":"https:\/\/bonsoleil.es\/?p=119867"},"modified":"2024-03-01T09:53:27","modified_gmt":"2024-03-01T08:53:27","slug":"forest-animals","status":"publish","type":"post","link":"https:\/\/bonsoleil.es\/es\/forest-animals\/","title":{"rendered":"Forest animals"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">The pupils from PS went on an exciting walk in the school\u2019s forest. Behind the trees they found a hidden squirrel, a bear, a deer, a fox and a bird and they sang a song for them.<br>__<br>Les \u00e9l\u00e8ves de la classe de PS ont fait une promenade passionnante dans la for\u00eat de l&#8217;\u00e9cole. Derri\u00e8re les arbres, cach\u00e9s, ils ont trouv\u00e9 un \u00e9cureuil, un ours, un cerf, un renard et un oiseau, et leur ont chant\u00e9 une chanson.<\/p>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-1 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/01\/2-9.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"700\" height=\"700\" data-id=\"119872\" src=\"https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/01\/2-9-700x700.jpg\" alt=\"\" class=\"wp-image-119872\" srcset=\"https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/01\/2-9-700x700.jpg 700w, https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/01\/2-9-250x250.jpg 250w, https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/01\/2-9-150x150.jpg 150w, https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/01\/2-9-768x768.jpg 768w, https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/01\/2-9-120x120.jpg 120w, https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/01\/2-9.jpg 1080w\" sizes=\"auto, (max-width: 700px) 100vw, 700px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/01\/3-9.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"700\" height=\"700\" data-id=\"119876\" src=\"https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/01\/3-9-700x700.jpg\" alt=\"\" class=\"wp-image-119876\" srcset=\"https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/01\/3-9-700x700.jpg 700w, https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/01\/3-9-250x250.jpg 250w, https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/01\/3-9-150x150.jpg 150w, https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/01\/3-9-768x768.jpg 768w, https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/01\/3-9-120x120.jpg 120w, https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/01\/3-9.jpg 1080w\" sizes=\"auto, (max-width: 700px) 100vw, 700px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/01\/5-8.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"700\" height=\"700\" data-id=\"119884\" src=\"https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/01\/5-8-700x700.jpg\" alt=\"\" class=\"wp-image-119884\" srcset=\"https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/01\/5-8-700x700.jpg 700w, https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/01\/5-8-250x250.jpg 250w, https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/01\/5-8-150x150.jpg 150w, https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/01\/5-8-768x768.jpg 768w, https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/01\/5-8-120x120.jpg 120w, https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/01\/5-8.jpg 1080w\" sizes=\"auto, (max-width: 700px) 100vw, 700px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/01\/6-7.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"700\" height=\"700\" data-id=\"119888\" src=\"https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/01\/6-7-700x700.jpg\" alt=\"\" class=\"wp-image-119888\" srcset=\"https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/01\/6-7-700x700.jpg 700w, https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/01\/6-7-250x250.jpg 250w, https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/01\/6-7-150x150.jpg 150w, https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/01\/6-7-768x768.jpg 768w, https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/01\/6-7-120x120.jpg 120w, https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/01\/6-7.jpg 1080w\" sizes=\"auto, (max-width: 700px) 100vw, 700px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/01\/7-3.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"700\" height=\"700\" data-id=\"119892\" src=\"https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/01\/7-3-700x700.jpg\" alt=\"\" class=\"wp-image-119892\" srcset=\"https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/01\/7-3-700x700.jpg 700w, https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/01\/7-3-250x250.jpg 250w, https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/01\/7-3-150x150.jpg 150w, https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/01\/7-3-768x768.jpg 768w, https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/01\/7-3-120x120.jpg 120w, https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/01\/7-3.jpg 1080w\" sizes=\"auto, (max-width: 700px) 100vw, 700px\" \/><\/a><\/figure>\n<\/figure>\n","protected":false},"excerpt":{"rendered":"The pupils from PS went on an exciting walk in the&#8230;","protected":false},"author":1,"featured_media":119880,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"rs_blank_template":"","rs_page_bg_color":"","slide_template_v7":"","footnotes":"","_links_to":"","_links_to_target":""},"categories":[14],"tags":[],"class_list":["post-119867","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-primaire"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Forest animals - Lyc\u00e9e International Barcelona \u00b7 Bon Soleil<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/bonsoleil.es\/es\/forest-animals\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Forest animals - Lyc\u00e9e International Barcelona \u00b7 Bon Soleil\" \/>\n<meta property=\"og:description\" content=\"The pupils from PS went on an exciting walk in the...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/bonsoleil.es\/es\/forest-animals\/\" \/>\n<meta property=\"og:site_name\" content=\"Lyc\u00e9e International Barcelona \u00b7 Bon Soleil\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/libBonSoleil\/\" \/>\n<meta property=\"article:published_time\" content=\"2024-01-09T08:34:47+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-03-01T08:53:27+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/01\/4-9-e1704789278681.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1080\" \/>\n\t<meta property=\"og:image:height\" content=\"687\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"libbs\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@lib_bonsoleil\" \/>\n<meta name=\"twitter:site\" content=\"@lib_bonsoleil\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"libbs\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/bonsoleil.es\\\/es\\\/forest-animals\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/bonsoleil.es\\\/es\\\/forest-animals\\\/\"},\"author\":{\"name\":\"libbs\",\"@id\":\"https:\\\/\\\/bonsoleil.es\\\/es\\\/#\\\/schema\\\/person\\\/f90f9175af4fad9c626fd2873bc546ec\"},\"headline\":\"Forest animals\",\"datePublished\":\"2024-01-09T08:34:47+00:00\",\"dateModified\":\"2024-03-01T08:53:27+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/bonsoleil.es\\\/es\\\/forest-animals\\\/\"},\"wordCount\":86,\"image\":{\"@id\":\"https:\\\/\\\/bonsoleil.es\\\/es\\\/forest-animals\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/bonsoleil.es\\\/web\\\/wp-content\\\/uploads\\\/2024\\\/01\\\/4-9-e1704789278681.jpg\",\"articleSection\":[\"Primaire\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/bonsoleil.es\\\/es\\\/forest-animals\\\/\",\"url\":\"https:\\\/\\\/bonsoleil.es\\\/es\\\/forest-animals\\\/\",\"name\":\"Forest animals - Lyc\u00e9e International Barcelona \u00b7 Bon Soleil\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/bonsoleil.es\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/bonsoleil.es\\\/es\\\/forest-animals\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/bonsoleil.es\\\/es\\\/forest-animals\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/bonsoleil.es\\\/web\\\/wp-content\\\/uploads\\\/2024\\\/01\\\/4-9-e1704789278681.jpg\",\"datePublished\":\"2024-01-09T08:34:47+00:00\",\"dateModified\":\"2024-03-01T08:53:27+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/bonsoleil.es\\\/es\\\/#\\\/schema\\\/person\\\/f90f9175af4fad9c626fd2873bc546ec\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/bonsoleil.es\\\/es\\\/forest-animals\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/bonsoleil.es\\\/es\\\/forest-animals\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/bonsoleil.es\\\/es\\\/forest-animals\\\/#primaryimage\",\"url\":\"https:\\\/\\\/bonsoleil.es\\\/web\\\/wp-content\\\/uploads\\\/2024\\\/01\\\/4-9-e1704789278681.jpg\",\"contentUrl\":\"https:\\\/\\\/bonsoleil.es\\\/web\\\/wp-content\\\/uploads\\\/2024\\\/01\\\/4-9-e1704789278681.jpg\",\"width\":1080,\"height\":687},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/bonsoleil.es\\\/es\\\/forest-animals\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/bonsoleil.es\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Forest animals\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/bonsoleil.es\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/bonsoleil.es\\\/es\\\/\",\"name\":\"Lyc\u00e9e International Barcelona \u00b7 Bon Soleil\",\"description\":\"Lyc\u00e9e International Barcelona\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/bonsoleil.es\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/bonsoleil.es\\\/es\\\/#\\\/schema\\\/person\\\/f90f9175af4fad9c626fd2873bc546ec\",\"name\":\"libbs\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/bonsoleil.es\\\/web\\\/wp-content\\\/litespeed\\\/avatar\\\/6719caedb5831fa7538835120a8121f8.jpg?ver=1783691672\",\"url\":\"https:\\\/\\\/bonsoleil.es\\\/web\\\/wp-content\\\/litespeed\\\/avatar\\\/6719caedb5831fa7538835120a8121f8.jpg?ver=1783691672\",\"contentUrl\":\"https:\\\/\\\/bonsoleil.es\\\/web\\\/wp-content\\\/litespeed\\\/avatar\\\/6719caedb5831fa7538835120a8121f8.jpg?ver=1783691672\",\"caption\":\"libbs\"},\"sameAs\":[\"http:\\\/\\\/localhost\\\/bonsoleil\\\/new_web\"],\"url\":\"https:\\\/\\\/bonsoleil.es\\\/es\\\/author\\\/libbs\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Forest animals - Lyc\u00e9e International Barcelona \u00b7 Bon Soleil","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/bonsoleil.es\/es\/forest-animals\/","og_locale":"es_ES","og_type":"article","og_title":"Forest animals - Lyc\u00e9e International Barcelona \u00b7 Bon Soleil","og_description":"The pupils from PS went on an exciting walk in the...","og_url":"https:\/\/bonsoleil.es\/es\/forest-animals\/","og_site_name":"Lyc\u00e9e International Barcelona \u00b7 Bon Soleil","article_publisher":"https:\/\/www.facebook.com\/libBonSoleil\/","article_published_time":"2024-01-09T08:34:47+00:00","article_modified_time":"2024-03-01T08:53:27+00:00","og_image":[{"width":1080,"height":687,"url":"https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/01\/4-9-e1704789278681.jpg","type":"image\/jpeg"}],"author":"libbs","twitter_card":"summary_large_image","twitter_creator":"@lib_bonsoleil","twitter_site":"@lib_bonsoleil","twitter_misc":{"Escrito por":"libbs","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/bonsoleil.es\/es\/forest-animals\/#article","isPartOf":{"@id":"https:\/\/bonsoleil.es\/es\/forest-animals\/"},"author":{"name":"libbs","@id":"https:\/\/bonsoleil.es\/es\/#\/schema\/person\/f90f9175af4fad9c626fd2873bc546ec"},"headline":"Forest animals","datePublished":"2024-01-09T08:34:47+00:00","dateModified":"2024-03-01T08:53:27+00:00","mainEntityOfPage":{"@id":"https:\/\/bonsoleil.es\/es\/forest-animals\/"},"wordCount":86,"image":{"@id":"https:\/\/bonsoleil.es\/es\/forest-animals\/#primaryimage"},"thumbnailUrl":"https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/01\/4-9-e1704789278681.jpg","articleSection":["Primaire"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/bonsoleil.es\/es\/forest-animals\/","url":"https:\/\/bonsoleil.es\/es\/forest-animals\/","name":"Forest animals - Lyc\u00e9e International Barcelona \u00b7 Bon Soleil","isPartOf":{"@id":"https:\/\/bonsoleil.es\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/bonsoleil.es\/es\/forest-animals\/#primaryimage"},"image":{"@id":"https:\/\/bonsoleil.es\/es\/forest-animals\/#primaryimage"},"thumbnailUrl":"https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/01\/4-9-e1704789278681.jpg","datePublished":"2024-01-09T08:34:47+00:00","dateModified":"2024-03-01T08:53:27+00:00","author":{"@id":"https:\/\/bonsoleil.es\/es\/#\/schema\/person\/f90f9175af4fad9c626fd2873bc546ec"},"breadcrumb":{"@id":"https:\/\/bonsoleil.es\/es\/forest-animals\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/bonsoleil.es\/es\/forest-animals\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/bonsoleil.es\/es\/forest-animals\/#primaryimage","url":"https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/01\/4-9-e1704789278681.jpg","contentUrl":"https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/01\/4-9-e1704789278681.jpg","width":1080,"height":687},{"@type":"BreadcrumbList","@id":"https:\/\/bonsoleil.es\/es\/forest-animals\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/bonsoleil.es\/es\/"},{"@type":"ListItem","position":2,"name":"Forest animals"}]},{"@type":"WebSite","@id":"https:\/\/bonsoleil.es\/es\/#website","url":"https:\/\/bonsoleil.es\/es\/","name":"Lyc\u00e9e International Barcelona \u00b7 Bon Soleil","description":"Lyc\u00e9e International Barcelona","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/bonsoleil.es\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/bonsoleil.es\/es\/#\/schema\/person\/f90f9175af4fad9c626fd2873bc546ec","name":"libbs","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/bonsoleil.es\/web\/wp-content\/litespeed\/avatar\/6719caedb5831fa7538835120a8121f8.jpg?ver=1783691672","url":"https:\/\/bonsoleil.es\/web\/wp-content\/litespeed\/avatar\/6719caedb5831fa7538835120a8121f8.jpg?ver=1783691672","contentUrl":"https:\/\/bonsoleil.es\/web\/wp-content\/litespeed\/avatar\/6719caedb5831fa7538835120a8121f8.jpg?ver=1783691672","caption":"libbs"},"sameAs":["http:\/\/localhost\/bonsoleil\/new_web"],"url":"https:\/\/bonsoleil.es\/es\/author\/libbs\/"}]}},"_links":{"self":[{"href":"https:\/\/bonsoleil.es\/es\/wp-json\/wp\/v2\/posts\/119867","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/bonsoleil.es\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/bonsoleil.es\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/bonsoleil.es\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/bonsoleil.es\/es\/wp-json\/wp\/v2\/comments?post=119867"}],"version-history":[{"count":3,"href":"https:\/\/bonsoleil.es\/es\/wp-json\/wp\/v2\/posts\/119867\/revisions"}],"predecessor-version":[{"id":122331,"href":"https:\/\/bonsoleil.es\/es\/wp-json\/wp\/v2\/posts\/119867\/revisions\/122331"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/bonsoleil.es\/es\/wp-json\/wp\/v2\/media\/119880"}],"wp:attachment":[{"href":"https:\/\/bonsoleil.es\/es\/wp-json\/wp\/v2\/media?parent=119867"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/bonsoleil.es\/es\/wp-json\/wp\/v2\/categories?post=119867"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/bonsoleil.es\/es\/wp-json\/wp\/v2\/tags?post=119867"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}