{"id":126645,"date":"2024-06-11T09:34:43","date_gmt":"2024-06-11T07:34:43","guid":{"rendered":"https:\/\/bonsoleil.es\/?p=126645"},"modified":"2024-06-11T09:37:49","modified_gmt":"2024-06-11T07:37:49","slug":"ceremonie-de-remise-des-diplomes-2024","status":"publish","type":"post","link":"https:\/\/bonsoleil.es\/es\/ceremonie-de-remise-des-diplomes-2024\/","title":{"rendered":"C\u00e9r\u00e9monie de Remise des Dipl\u00f4mes 2024"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">F\u00e9licitations \u00e0 toute la promotion du Baccalaur\u00e9at 2024 ! Nous c\u00e9l\u00e9brons non seulement la fin d&#8217;une \u00e9tape, mais aussi le d\u00e9but d&#8217;une nouvelle \u00e9tape pleine d&#8217;opportunit\u00e9s et de r\u00eaves \u00e0 r\u00e9aliser. Nous sommes fiers de voir comment chacun d&#8217;entre vous a grandi et surmont\u00e9 des d\u00e9fis pour en arriver l\u00e0. Cette r\u00e9ussite n&#8217;est que le d\u00e9but d&#8217;un voyage incroyable &#8211; merci de nous avoir permis de faire partie de votre voyage et de votre succ\u00e8s ! \ud83c\udf89\ud83d\udcda<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">_<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00a1Felicidades a la promoci\u00f3n de bachillerato 2024! \ud83c\udf93\u2728 Celebramos no solo el final de una etapa, sino el comienzo de una nueva llena de oportunidades y sue\u00f1os por cumplir. Nos enorgullece ver c\u00f3mo cada uno de vosotros ha crecido y superado desaf\u00edos para llegar hasta aqu\u00ed. Este logro es solo el comienzo de un viaje incre\u00edble. \u00a1Gracias por permitirnos ser parte de este camino y \u00e9xito! \ud83c\udf89\ud83d\udcda<\/p>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-1 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-full\"><a href=\"https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/06\/DSC_0006-Medium.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"1152\" height=\"768\" data-id=\"126646\" src=\"https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/06\/DSC_0006-Medium.jpg\" alt=\"\" class=\"wp-image-126646\" srcset=\"https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/06\/DSC_0006-Medium.jpg 1152w, https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/06\/DSC_0006-Medium-250x167.jpg 250w, https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/06\/DSC_0006-Medium-700x467.jpg 700w, https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/06\/DSC_0006-Medium-768x512.jpg 768w, https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/06\/DSC_0006-Medium-120x80.jpg 120w\" sizes=\"auto, (max-width: 1152px) 100vw, 1152px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-full\"><a href=\"https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/06\/DSC_0011-Medium.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"1152\" height=\"768\" data-id=\"126650\" src=\"https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/06\/DSC_0011-Medium.jpg\" alt=\"\" class=\"wp-image-126650\" srcset=\"https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/06\/DSC_0011-Medium.jpg 1152w, https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/06\/DSC_0011-Medium-250x167.jpg 250w, https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/06\/DSC_0011-Medium-700x467.jpg 700w, https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/06\/DSC_0011-Medium-768x512.jpg 768w, https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/06\/DSC_0011-Medium-120x80.jpg 120w\" sizes=\"auto, (max-width: 1152px) 100vw, 1152px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-full\"><a href=\"https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/06\/DSC_0014-Medium.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"1152\" height=\"768\" data-id=\"126654\" src=\"https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/06\/DSC_0014-Medium.jpg\" alt=\"\" class=\"wp-image-126654\" srcset=\"https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/06\/DSC_0014-Medium.jpg 1152w, https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/06\/DSC_0014-Medium-250x167.jpg 250w, https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/06\/DSC_0014-Medium-700x467.jpg 700w, https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/06\/DSC_0014-Medium-768x512.jpg 768w, https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/06\/DSC_0014-Medium-120x80.jpg 120w\" sizes=\"auto, (max-width: 1152px) 100vw, 1152px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-full\"><a href=\"https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/06\/DSC_0026-Medium.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"1152\" height=\"768\" data-id=\"126658\" src=\"https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/06\/DSC_0026-Medium.jpg\" alt=\"\" class=\"wp-image-126658\" srcset=\"https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/06\/DSC_0026-Medium.jpg 1152w, https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/06\/DSC_0026-Medium-250x167.jpg 250w, https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/06\/DSC_0026-Medium-700x467.jpg 700w, https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/06\/DSC_0026-Medium-768x512.jpg 768w, https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/06\/DSC_0026-Medium-120x80.jpg 120w\" sizes=\"auto, (max-width: 1152px) 100vw, 1152px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-full\"><a href=\"https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/06\/DSC_0027-Medium.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"1152\" height=\"768\" data-id=\"126662\" src=\"https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/06\/DSC_0027-Medium.jpg\" alt=\"\" class=\"wp-image-126662\" srcset=\"https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/06\/DSC_0027-Medium.jpg 1152w, https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/06\/DSC_0027-Medium-250x167.jpg 250w, https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/06\/DSC_0027-Medium-700x467.jpg 700w, https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/06\/DSC_0027-Medium-768x512.jpg 768w, https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/06\/DSC_0027-Medium-120x80.jpg 120w\" sizes=\"auto, (max-width: 1152px) 100vw, 1152px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-full\"><a href=\"https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/06\/DSC_0035-Medium.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"1152\" height=\"768\" data-id=\"126666\" src=\"https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/06\/DSC_0035-Medium.jpg\" alt=\"\" class=\"wp-image-126666\" srcset=\"https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/06\/DSC_0035-Medium.jpg 1152w, https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/06\/DSC_0035-Medium-250x167.jpg 250w, https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/06\/DSC_0035-Medium-700x467.jpg 700w, https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/06\/DSC_0035-Medium-768x512.jpg 768w, https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/06\/DSC_0035-Medium-120x80.jpg 120w\" sizes=\"auto, (max-width: 1152px) 100vw, 1152px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-full\"><a href=\"https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/06\/DSC_0036-Medium.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"1152\" height=\"768\" data-id=\"126670\" src=\"https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/06\/DSC_0036-Medium.jpg\" alt=\"\" class=\"wp-image-126670\" srcset=\"https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/06\/DSC_0036-Medium.jpg 1152w, https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/06\/DSC_0036-Medium-250x167.jpg 250w, https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/06\/DSC_0036-Medium-700x467.jpg 700w, https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/06\/DSC_0036-Medium-768x512.jpg 768w, https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/06\/DSC_0036-Medium-120x80.jpg 120w\" sizes=\"auto, (max-width: 1152px) 100vw, 1152px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-full\"><a href=\"https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/06\/DSC_0042-Medium.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"1152\" height=\"768\" data-id=\"126674\" src=\"https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/06\/DSC_0042-Medium.jpg\" alt=\"\" class=\"wp-image-126674\" srcset=\"https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/06\/DSC_0042-Medium.jpg 1152w, https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/06\/DSC_0042-Medium-250x167.jpg 250w, https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/06\/DSC_0042-Medium-700x467.jpg 700w, https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/06\/DSC_0042-Medium-768x512.jpg 768w, https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/06\/DSC_0042-Medium-120x80.jpg 120w\" sizes=\"auto, (max-width: 1152px) 100vw, 1152px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-full\"><a href=\"https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/06\/DSC_0043-Medium.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"1152\" height=\"768\" data-id=\"126678\" src=\"https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/06\/DSC_0043-Medium.jpg\" alt=\"\" class=\"wp-image-126678\" srcset=\"https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/06\/DSC_0043-Medium.jpg 1152w, https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/06\/DSC_0043-Medium-250x167.jpg 250w, https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/06\/DSC_0043-Medium-700x467.jpg 700w, https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/06\/DSC_0043-Medium-768x512.jpg 768w, https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/06\/DSC_0043-Medium-120x80.jpg 120w\" sizes=\"auto, (max-width: 1152px) 100vw, 1152px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-full\"><a href=\"https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/06\/DSC_0044-Medium.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"1152\" height=\"768\" data-id=\"126682\" src=\"https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/06\/DSC_0044-Medium.jpg\" alt=\"\" class=\"wp-image-126682\" srcset=\"https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/06\/DSC_0044-Medium.jpg 1152w, https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/06\/DSC_0044-Medium-250x167.jpg 250w, https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/06\/DSC_0044-Medium-700x467.jpg 700w, https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/06\/DSC_0044-Medium-768x512.jpg 768w, https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/06\/DSC_0044-Medium-120x80.jpg 120w\" sizes=\"auto, (max-width: 1152px) 100vw, 1152px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-full\"><a href=\"https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/06\/DSC_0045-Medium.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"1152\" height=\"768\" data-id=\"126686\" src=\"https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/06\/DSC_0045-Medium.jpg\" alt=\"\" class=\"wp-image-126686\" srcset=\"https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/06\/DSC_0045-Medium.jpg 1152w, https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/06\/DSC_0045-Medium-250x167.jpg 250w, https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/06\/DSC_0045-Medium-700x467.jpg 700w, https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/06\/DSC_0045-Medium-768x512.jpg 768w, https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/06\/DSC_0045-Medium-120x80.jpg 120w\" sizes=\"auto, (max-width: 1152px) 100vw, 1152px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-full\"><a href=\"https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/06\/DSC_0050-Medium.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"1152\" height=\"768\" data-id=\"126690\" src=\"https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/06\/DSC_0050-Medium.jpg\" alt=\"\" class=\"wp-image-126690\" srcset=\"https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/06\/DSC_0050-Medium.jpg 1152w, https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/06\/DSC_0050-Medium-250x167.jpg 250w, https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/06\/DSC_0050-Medium-700x467.jpg 700w, https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/06\/DSC_0050-Medium-768x512.jpg 768w, https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/06\/DSC_0050-Medium-120x80.jpg 120w\" sizes=\"auto, (max-width: 1152px) 100vw, 1152px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-full\"><a href=\"https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/06\/DSC_0052-Medium.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"1152\" height=\"768\" data-id=\"126694\" src=\"https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/06\/DSC_0052-Medium.jpg\" alt=\"\" class=\"wp-image-126694\" srcset=\"https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/06\/DSC_0052-Medium.jpg 1152w, https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/06\/DSC_0052-Medium-250x167.jpg 250w, https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/06\/DSC_0052-Medium-700x467.jpg 700w, https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/06\/DSC_0052-Medium-768x512.jpg 768w, https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/06\/DSC_0052-Medium-120x80.jpg 120w\" sizes=\"auto, (max-width: 1152px) 100vw, 1152px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-full\"><a href=\"https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/06\/DSC_0053-Medium.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"1152\" height=\"768\" data-id=\"126698\" src=\"https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/06\/DSC_0053-Medium.jpg\" alt=\"\" class=\"wp-image-126698\" srcset=\"https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/06\/DSC_0053-Medium.jpg 1152w, https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/06\/DSC_0053-Medium-250x167.jpg 250w, https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/06\/DSC_0053-Medium-700x467.jpg 700w, https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/06\/DSC_0053-Medium-768x512.jpg 768w, https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/06\/DSC_0053-Medium-120x80.jpg 120w\" sizes=\"auto, (max-width: 1152px) 100vw, 1152px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-full\"><a href=\"https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/06\/DSC_0065-Medium.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"1152\" height=\"768\" data-id=\"126702\" src=\"https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/06\/DSC_0065-Medium.jpg\" alt=\"\" class=\"wp-image-126702\" srcset=\"https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/06\/DSC_0065-Medium.jpg 1152w, https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/06\/DSC_0065-Medium-250x167.jpg 250w, https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/06\/DSC_0065-Medium-700x467.jpg 700w, https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/06\/DSC_0065-Medium-768x512.jpg 768w, https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/06\/DSC_0065-Medium-120x80.jpg 120w\" sizes=\"auto, (max-width: 1152px) 100vw, 1152px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-full\"><a href=\"https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/06\/DSC_0066-Medium.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"1152\" height=\"768\" data-id=\"126706\" src=\"https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/06\/DSC_0066-Medium.jpg\" alt=\"\" class=\"wp-image-126706\" srcset=\"https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/06\/DSC_0066-Medium.jpg 1152w, https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/06\/DSC_0066-Medium-250x167.jpg 250w, https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/06\/DSC_0066-Medium-700x467.jpg 700w, https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/06\/DSC_0066-Medium-768x512.jpg 768w, https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/06\/DSC_0066-Medium-120x80.jpg 120w\" sizes=\"auto, (max-width: 1152px) 100vw, 1152px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-full\"><a href=\"https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/06\/DSC_0067-Medium.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"1152\" height=\"768\" data-id=\"126710\" src=\"https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/06\/DSC_0067-Medium.jpg\" alt=\"\" class=\"wp-image-126710\" srcset=\"https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/06\/DSC_0067-Medium.jpg 1152w, https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/06\/DSC_0067-Medium-250x167.jpg 250w, https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/06\/DSC_0067-Medium-700x467.jpg 700w, https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/06\/DSC_0067-Medium-768x512.jpg 768w, https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/06\/DSC_0067-Medium-120x80.jpg 120w\" sizes=\"auto, (max-width: 1152px) 100vw, 1152px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-full\"><a href=\"https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/06\/DSC_0069-Medium.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"1152\" height=\"768\" data-id=\"126714\" src=\"https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/06\/DSC_0069-Medium.jpg\" alt=\"\" class=\"wp-image-126714\" srcset=\"https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/06\/DSC_0069-Medium.jpg 1152w, https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/06\/DSC_0069-Medium-250x167.jpg 250w, https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/06\/DSC_0069-Medium-700x467.jpg 700w, https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/06\/DSC_0069-Medium-768x512.jpg 768w, https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/06\/DSC_0069-Medium-120x80.jpg 120w\" sizes=\"auto, (max-width: 1152px) 100vw, 1152px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-full\"><a href=\"https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/06\/DSC_0072-Medium.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"1152\" height=\"768\" data-id=\"126718\" src=\"https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/06\/DSC_0072-Medium.jpg\" alt=\"\" class=\"wp-image-126718\" srcset=\"https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/06\/DSC_0072-Medium.jpg 1152w, https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/06\/DSC_0072-Medium-250x167.jpg 250w, https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/06\/DSC_0072-Medium-700x467.jpg 700w, https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/06\/DSC_0072-Medium-768x512.jpg 768w, https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/06\/DSC_0072-Medium-120x80.jpg 120w\" sizes=\"auto, (max-width: 1152px) 100vw, 1152px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-full\"><a href=\"https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/06\/DSC_0076-Medium.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"1152\" height=\"768\" data-id=\"126722\" src=\"https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/06\/DSC_0076-Medium.jpg\" alt=\"\" class=\"wp-image-126722\" srcset=\"https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/06\/DSC_0076-Medium.jpg 1152w, https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/06\/DSC_0076-Medium-250x167.jpg 250w, https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/06\/DSC_0076-Medium-700x467.jpg 700w, https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/06\/DSC_0076-Medium-768x512.jpg 768w, https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/06\/DSC_0076-Medium-120x80.jpg 120w\" sizes=\"auto, (max-width: 1152px) 100vw, 1152px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-full\"><a href=\"https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/06\/DSC_0077-Medium.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"1152\" height=\"768\" data-id=\"126726\" src=\"https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/06\/DSC_0077-Medium.jpg\" alt=\"\" class=\"wp-image-126726\" srcset=\"https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/06\/DSC_0077-Medium.jpg 1152w, https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/06\/DSC_0077-Medium-250x167.jpg 250w, https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/06\/DSC_0077-Medium-700x467.jpg 700w, https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/06\/DSC_0077-Medium-768x512.jpg 768w, https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/06\/DSC_0077-Medium-120x80.jpg 120w\" sizes=\"auto, (max-width: 1152px) 100vw, 1152px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-full\"><a href=\"https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/06\/DSC_0080-Medium.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"1152\" height=\"768\" data-id=\"126730\" src=\"https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/06\/DSC_0080-Medium.jpg\" alt=\"\" class=\"wp-image-126730\" srcset=\"https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/06\/DSC_0080-Medium.jpg 1152w, https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/06\/DSC_0080-Medium-250x167.jpg 250w, https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/06\/DSC_0080-Medium-700x467.jpg 700w, https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/06\/DSC_0080-Medium-768x512.jpg 768w, https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/06\/DSC_0080-Medium-120x80.jpg 120w\" sizes=\"auto, (max-width: 1152px) 100vw, 1152px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-full\"><a href=\"https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/06\/DSC_0082-Medium.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"1152\" height=\"768\" data-id=\"126734\" src=\"https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/06\/DSC_0082-Medium.jpg\" alt=\"\" class=\"wp-image-126734\" srcset=\"https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/06\/DSC_0082-Medium.jpg 1152w, https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/06\/DSC_0082-Medium-250x167.jpg 250w, https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/06\/DSC_0082-Medium-700x467.jpg 700w, https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/06\/DSC_0082-Medium-768x512.jpg 768w, https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/06\/DSC_0082-Medium-120x80.jpg 120w\" sizes=\"auto, (max-width: 1152px) 100vw, 1152px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-full\"><a href=\"https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/06\/DSC_0083-Medium.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"1152\" height=\"768\" data-id=\"126738\" src=\"https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/06\/DSC_0083-Medium.jpg\" alt=\"\" class=\"wp-image-126738\" srcset=\"https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/06\/DSC_0083-Medium.jpg 1152w, https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/06\/DSC_0083-Medium-250x167.jpg 250w, https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/06\/DSC_0083-Medium-700x467.jpg 700w, https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/06\/DSC_0083-Medium-768x512.jpg 768w, https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/06\/DSC_0083-Medium-120x80.jpg 120w\" sizes=\"auto, (max-width: 1152px) 100vw, 1152px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-full\"><a href=\"https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/06\/DSC_0087-Medium.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"1152\" height=\"768\" data-id=\"126742\" src=\"https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/06\/DSC_0087-Medium.jpg\" alt=\"\" class=\"wp-image-126742\" srcset=\"https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/06\/DSC_0087-Medium.jpg 1152w, https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/06\/DSC_0087-Medium-250x167.jpg 250w, https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/06\/DSC_0087-Medium-700x467.jpg 700w, https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/06\/DSC_0087-Medium-768x512.jpg 768w, https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/06\/DSC_0087-Medium-120x80.jpg 120w\" sizes=\"auto, (max-width: 1152px) 100vw, 1152px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-full\"><a href=\"https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/06\/DSC_0093-Medium.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"1152\" height=\"768\" data-id=\"126746\" src=\"https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/06\/DSC_0093-Medium.jpg\" alt=\"\" class=\"wp-image-126746\" srcset=\"https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/06\/DSC_0093-Medium.jpg 1152w, https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/06\/DSC_0093-Medium-250x167.jpg 250w, https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/06\/DSC_0093-Medium-700x467.jpg 700w, https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/06\/DSC_0093-Medium-768x512.jpg 768w, https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/06\/DSC_0093-Medium-120x80.jpg 120w\" sizes=\"auto, (max-width: 1152px) 100vw, 1152px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-full\"><a href=\"https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/06\/DSC_0098-Medium.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"1152\" height=\"768\" data-id=\"126750\" src=\"https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/06\/DSC_0098-Medium.jpg\" alt=\"\" class=\"wp-image-126750\" srcset=\"https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/06\/DSC_0098-Medium.jpg 1152w, https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/06\/DSC_0098-Medium-250x167.jpg 250w, https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/06\/DSC_0098-Medium-700x467.jpg 700w, https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/06\/DSC_0098-Medium-768x512.jpg 768w, https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/06\/DSC_0098-Medium-120x80.jpg 120w\" sizes=\"auto, (max-width: 1152px) 100vw, 1152px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-full\"><a href=\"https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/06\/DSC_0099-Medium.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"1152\" height=\"768\" data-id=\"126754\" src=\"https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/06\/DSC_0099-Medium.jpg\" alt=\"\" class=\"wp-image-126754\" srcset=\"https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/06\/DSC_0099-Medium.jpg 1152w, https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/06\/DSC_0099-Medium-250x167.jpg 250w, https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/06\/DSC_0099-Medium-700x467.jpg 700w, https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/06\/DSC_0099-Medium-768x512.jpg 768w, https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/06\/DSC_0099-Medium-120x80.jpg 120w\" sizes=\"auto, (max-width: 1152px) 100vw, 1152px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-full\"><a href=\"https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/06\/DSC_0103-Medium.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"1152\" height=\"768\" data-id=\"126758\" src=\"https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/06\/DSC_0103-Medium.jpg\" alt=\"\" class=\"wp-image-126758\" srcset=\"https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/06\/DSC_0103-Medium.jpg 1152w, https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/06\/DSC_0103-Medium-250x167.jpg 250w, https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/06\/DSC_0103-Medium-700x467.jpg 700w, https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/06\/DSC_0103-Medium-768x512.jpg 768w, https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/06\/DSC_0103-Medium-120x80.jpg 120w\" sizes=\"auto, (max-width: 1152px) 100vw, 1152px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-full\"><a href=\"https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/06\/DSC_0104-Medium.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"1152\" height=\"768\" data-id=\"126762\" src=\"https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/06\/DSC_0104-Medium.jpg\" alt=\"\" class=\"wp-image-126762\" srcset=\"https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/06\/DSC_0104-Medium.jpg 1152w, https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/06\/DSC_0104-Medium-250x167.jpg 250w, https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/06\/DSC_0104-Medium-700x467.jpg 700w, https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/06\/DSC_0104-Medium-768x512.jpg 768w, https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/06\/DSC_0104-Medium-120x80.jpg 120w\" sizes=\"auto, (max-width: 1152px) 100vw, 1152px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-full\"><a href=\"https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/06\/DSC_0107-Medium.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"1152\" height=\"768\" data-id=\"126766\" src=\"https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/06\/DSC_0107-Medium.jpg\" alt=\"\" class=\"wp-image-126766\" srcset=\"https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/06\/DSC_0107-Medium.jpg 1152w, https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/06\/DSC_0107-Medium-250x167.jpg 250w, https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/06\/DSC_0107-Medium-700x467.jpg 700w, https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/06\/DSC_0107-Medium-768x512.jpg 768w, https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/06\/DSC_0107-Medium-120x80.jpg 120w\" sizes=\"auto, (max-width: 1152px) 100vw, 1152px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-full\"><a href=\"https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/06\/DSC_0114-Medium.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"1152\" height=\"768\" data-id=\"126770\" src=\"https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/06\/DSC_0114-Medium.jpg\" alt=\"\" class=\"wp-image-126770\" srcset=\"https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/06\/DSC_0114-Medium.jpg 1152w, https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/06\/DSC_0114-Medium-250x167.jpg 250w, https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/06\/DSC_0114-Medium-700x467.jpg 700w, https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/06\/DSC_0114-Medium-768x512.jpg 768w, https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/06\/DSC_0114-Medium-120x80.jpg 120w\" sizes=\"auto, (max-width: 1152px) 100vw, 1152px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-full\"><a href=\"https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/06\/DSC_0115-Medium.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"1152\" height=\"768\" data-id=\"126774\" src=\"https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/06\/DSC_0115-Medium.jpg\" alt=\"\" class=\"wp-image-126774\" srcset=\"https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/06\/DSC_0115-Medium.jpg 1152w, https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/06\/DSC_0115-Medium-250x167.jpg 250w, https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/06\/DSC_0115-Medium-700x467.jpg 700w, https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/06\/DSC_0115-Medium-768x512.jpg 768w, https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/06\/DSC_0115-Medium-120x80.jpg 120w\" sizes=\"auto, (max-width: 1152px) 100vw, 1152px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-full\"><a href=\"https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/06\/DSC_0121-Medium.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"1152\" height=\"768\" data-id=\"126778\" src=\"https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/06\/DSC_0121-Medium.jpg\" alt=\"\" class=\"wp-image-126778\" srcset=\"https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/06\/DSC_0121-Medium.jpg 1152w, https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/06\/DSC_0121-Medium-250x167.jpg 250w, https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/06\/DSC_0121-Medium-700x467.jpg 700w, https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/06\/DSC_0121-Medium-768x512.jpg 768w, https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/06\/DSC_0121-Medium-120x80.jpg 120w\" sizes=\"auto, (max-width: 1152px) 100vw, 1152px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-full\"><a href=\"https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/06\/DSC_0143-Medium.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"1152\" height=\"768\" data-id=\"126782\" src=\"https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/06\/DSC_0143-Medium.jpg\" alt=\"\" class=\"wp-image-126782\" srcset=\"https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/06\/DSC_0143-Medium.jpg 1152w, https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/06\/DSC_0143-Medium-250x167.jpg 250w, https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/06\/DSC_0143-Medium-700x467.jpg 700w, https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/06\/DSC_0143-Medium-768x512.jpg 768w, https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/06\/DSC_0143-Medium-120x80.jpg 120w\" sizes=\"auto, (max-width: 1152px) 100vw, 1152px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-full\"><a href=\"https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/06\/DSC_0145-Medium.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"1152\" height=\"768\" data-id=\"126786\" src=\"https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/06\/DSC_0145-Medium.jpg\" alt=\"\" class=\"wp-image-126786\" srcset=\"https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/06\/DSC_0145-Medium.jpg 1152w, https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/06\/DSC_0145-Medium-250x167.jpg 250w, https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/06\/DSC_0145-Medium-700x467.jpg 700w, https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/06\/DSC_0145-Medium-768x512.jpg 768w, https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/06\/DSC_0145-Medium-120x80.jpg 120w\" sizes=\"auto, (max-width: 1152px) 100vw, 1152px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-full\"><a href=\"https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/06\/DSC_0148-Medium.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"1152\" height=\"768\" data-id=\"126790\" src=\"https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/06\/DSC_0148-Medium.jpg\" alt=\"\" class=\"wp-image-126790\" srcset=\"https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/06\/DSC_0148-Medium.jpg 1152w, https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/06\/DSC_0148-Medium-250x167.jpg 250w, https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/06\/DSC_0148-Medium-700x467.jpg 700w, https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/06\/DSC_0148-Medium-768x512.jpg 768w, https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/06\/DSC_0148-Medium-120x80.jpg 120w\" sizes=\"auto, (max-width: 1152px) 100vw, 1152px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-full\"><a href=\"https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/06\/DSC_0149-Medium.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"1152\" height=\"768\" data-id=\"126796\" src=\"https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/06\/DSC_0149-Medium.jpg\" alt=\"\" class=\"wp-image-126796\" srcset=\"https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/06\/DSC_0149-Medium.jpg 1152w, https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/06\/DSC_0149-Medium-250x167.jpg 250w, https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/06\/DSC_0149-Medium-700x467.jpg 700w, https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/06\/DSC_0149-Medium-768x512.jpg 768w, https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/06\/DSC_0149-Medium-120x80.jpg 120w\" sizes=\"auto, (max-width: 1152px) 100vw, 1152px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-full\"><a href=\"https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/06\/DSC_0152-Medium.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"1152\" height=\"768\" data-id=\"126800\" src=\"https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/06\/DSC_0152-Medium.jpg\" alt=\"\" class=\"wp-image-126800\" srcset=\"https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/06\/DSC_0152-Medium.jpg 1152w, https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/06\/DSC_0152-Medium-250x167.jpg 250w, https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/06\/DSC_0152-Medium-700x467.jpg 700w, https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/06\/DSC_0152-Medium-768x512.jpg 768w, https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/06\/DSC_0152-Medium-120x80.jpg 120w\" sizes=\"auto, (max-width: 1152px) 100vw, 1152px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-full\"><a href=\"https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/06\/DSC_0157-Medium.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"1152\" height=\"768\" data-id=\"126804\" src=\"https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/06\/DSC_0157-Medium.jpg\" alt=\"\" class=\"wp-image-126804\" srcset=\"https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/06\/DSC_0157-Medium.jpg 1152w, https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/06\/DSC_0157-Medium-250x167.jpg 250w, https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/06\/DSC_0157-Medium-700x467.jpg 700w, https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/06\/DSC_0157-Medium-768x512.jpg 768w, https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/06\/DSC_0157-Medium-120x80.jpg 120w\" sizes=\"auto, (max-width: 1152px) 100vw, 1152px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-full\"><a href=\"https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/06\/DSC_0159-Medium.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"1152\" height=\"768\" data-id=\"126808\" src=\"https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/06\/DSC_0159-Medium.jpg\" alt=\"\" class=\"wp-image-126808\" srcset=\"https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/06\/DSC_0159-Medium.jpg 1152w, https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/06\/DSC_0159-Medium-250x167.jpg 250w, https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/06\/DSC_0159-Medium-700x467.jpg 700w, https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/06\/DSC_0159-Medium-768x512.jpg 768w, https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/06\/DSC_0159-Medium-120x80.jpg 120w\" sizes=\"auto, (max-width: 1152px) 100vw, 1152px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-full\"><a href=\"https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/06\/DSC_0172-Medium.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"1152\" height=\"768\" data-id=\"126812\" src=\"https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/06\/DSC_0172-Medium.jpg\" alt=\"\" class=\"wp-image-126812\" srcset=\"https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/06\/DSC_0172-Medium.jpg 1152w, https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/06\/DSC_0172-Medium-250x167.jpg 250w, https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/06\/DSC_0172-Medium-700x467.jpg 700w, https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/06\/DSC_0172-Medium-768x512.jpg 768w, https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/06\/DSC_0172-Medium-120x80.jpg 120w\" sizes=\"auto, (max-width: 1152px) 100vw, 1152px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-full\"><a href=\"https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/06\/DSC_0173-Medium.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"1152\" height=\"768\" data-id=\"126816\" src=\"https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/06\/DSC_0173-Medium.jpg\" alt=\"\" class=\"wp-image-126816\" srcset=\"https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/06\/DSC_0173-Medium.jpg 1152w, https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/06\/DSC_0173-Medium-250x167.jpg 250w, https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/06\/DSC_0173-Medium-700x467.jpg 700w, https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/06\/DSC_0173-Medium-768x512.jpg 768w, https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/06\/DSC_0173-Medium-120x80.jpg 120w\" sizes=\"auto, (max-width: 1152px) 100vw, 1152px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-full\"><a href=\"https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/06\/DSC_0176-Medium.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"1152\" height=\"768\" data-id=\"126820\" src=\"https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/06\/DSC_0176-Medium.jpg\" alt=\"\" class=\"wp-image-126820\" srcset=\"https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/06\/DSC_0176-Medium.jpg 1152w, https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/06\/DSC_0176-Medium-250x167.jpg 250w, https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/06\/DSC_0176-Medium-700x467.jpg 700w, https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/06\/DSC_0176-Medium-768x512.jpg 768w, https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/06\/DSC_0176-Medium-120x80.jpg 120w\" sizes=\"auto, (max-width: 1152px) 100vw, 1152px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-full\"><a href=\"https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/06\/DSC_0188-Medium.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"1152\" height=\"768\" data-id=\"126824\" src=\"https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/06\/DSC_0188-Medium.jpg\" alt=\"\" class=\"wp-image-126824\" srcset=\"https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/06\/DSC_0188-Medium.jpg 1152w, https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/06\/DSC_0188-Medium-250x167.jpg 250w, https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/06\/DSC_0188-Medium-700x467.jpg 700w, https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/06\/DSC_0188-Medium-768x512.jpg 768w, https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/06\/DSC_0188-Medium-120x80.jpg 120w\" sizes=\"auto, (max-width: 1152px) 100vw, 1152px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-full\"><a href=\"https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/06\/DSC_0197-Medium.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"1152\" height=\"768\" data-id=\"126828\" src=\"https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/06\/DSC_0197-Medium.jpg\" alt=\"\" class=\"wp-image-126828\" srcset=\"https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/06\/DSC_0197-Medium.jpg 1152w, https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/06\/DSC_0197-Medium-250x167.jpg 250w, https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/06\/DSC_0197-Medium-700x467.jpg 700w, https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/06\/DSC_0197-Medium-768x512.jpg 768w, https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/06\/DSC_0197-Medium-120x80.jpg 120w\" sizes=\"auto, (max-width: 1152px) 100vw, 1152px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-full\"><a href=\"https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/06\/DSC_0199-Medium.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"1152\" height=\"768\" data-id=\"126832\" src=\"https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/06\/DSC_0199-Medium.jpg\" alt=\"\" class=\"wp-image-126832\" srcset=\"https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/06\/DSC_0199-Medium.jpg 1152w, https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/06\/DSC_0199-Medium-250x167.jpg 250w, https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/06\/DSC_0199-Medium-700x467.jpg 700w, https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/06\/DSC_0199-Medium-768x512.jpg 768w, https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/06\/DSC_0199-Medium-120x80.jpg 120w\" sizes=\"auto, (max-width: 1152px) 100vw, 1152px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-full\"><a href=\"https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/06\/DSC_0200-Medium.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"1152\" height=\"768\" data-id=\"126836\" src=\"https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/06\/DSC_0200-Medium.jpg\" alt=\"\" class=\"wp-image-126836\" srcset=\"https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/06\/DSC_0200-Medium.jpg 1152w, https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/06\/DSC_0200-Medium-250x167.jpg 250w, https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/06\/DSC_0200-Medium-700x467.jpg 700w, https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/06\/DSC_0200-Medium-768x512.jpg 768w, https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/06\/DSC_0200-Medium-120x80.jpg 120w\" sizes=\"auto, (max-width: 1152px) 100vw, 1152px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-full\"><a href=\"https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/06\/DSC_0201-Medium.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"1152\" height=\"768\" data-id=\"126840\" src=\"https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/06\/DSC_0201-Medium.jpg\" alt=\"\" class=\"wp-image-126840\" srcset=\"https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/06\/DSC_0201-Medium.jpg 1152w, https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/06\/DSC_0201-Medium-250x167.jpg 250w, https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/06\/DSC_0201-Medium-700x467.jpg 700w, https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/06\/DSC_0201-Medium-768x512.jpg 768w, https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/06\/DSC_0201-Medium-120x80.jpg 120w\" sizes=\"auto, (max-width: 1152px) 100vw, 1152px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-full\"><a href=\"https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/06\/DSC_0209-Medium.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"1152\" height=\"768\" data-id=\"126844\" src=\"https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/06\/DSC_0209-Medium.jpg\" alt=\"\" class=\"wp-image-126844\" srcset=\"https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/06\/DSC_0209-Medium.jpg 1152w, https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/06\/DSC_0209-Medium-250x167.jpg 250w, https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/06\/DSC_0209-Medium-700x467.jpg 700w, https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/06\/DSC_0209-Medium-768x512.jpg 768w, https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/06\/DSC_0209-Medium-120x80.jpg 120w\" sizes=\"auto, (max-width: 1152px) 100vw, 1152px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-full\"><a href=\"https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/06\/DSC_0214-Medium.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"1152\" height=\"768\" data-id=\"126848\" src=\"https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/06\/DSC_0214-Medium.jpg\" alt=\"\" class=\"wp-image-126848\" srcset=\"https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/06\/DSC_0214-Medium.jpg 1152w, https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/06\/DSC_0214-Medium-250x167.jpg 250w, https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/06\/DSC_0214-Medium-700x467.jpg 700w, https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/06\/DSC_0214-Medium-768x512.jpg 768w, https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/06\/DSC_0214-Medium-120x80.jpg 120w\" sizes=\"auto, (max-width: 1152px) 100vw, 1152px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-full\"><a href=\"https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/06\/DSC_0228-Medium.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"1152\" height=\"768\" data-id=\"126852\" src=\"https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/06\/DSC_0228-Medium.jpg\" alt=\"\" class=\"wp-image-126852\" srcset=\"https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/06\/DSC_0228-Medium.jpg 1152w, https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/06\/DSC_0228-Medium-250x167.jpg 250w, https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/06\/DSC_0228-Medium-700x467.jpg 700w, https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/06\/DSC_0228-Medium-768x512.jpg 768w, https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/06\/DSC_0228-Medium-120x80.jpg 120w\" sizes=\"auto, (max-width: 1152px) 100vw, 1152px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-full\"><a href=\"https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/06\/DSC_0230-Medium.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"1152\" height=\"768\" data-id=\"126856\" src=\"https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/06\/DSC_0230-Medium.jpg\" alt=\"\" class=\"wp-image-126856\" srcset=\"https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/06\/DSC_0230-Medium.jpg 1152w, https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/06\/DSC_0230-Medium-250x167.jpg 250w, https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/06\/DSC_0230-Medium-700x467.jpg 700w, https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/06\/DSC_0230-Medium-768x512.jpg 768w, https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/06\/DSC_0230-Medium-120x80.jpg 120w\" sizes=\"auto, (max-width: 1152px) 100vw, 1152px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-full\"><a href=\"https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/06\/DSC_0231-Medium.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"1152\" height=\"768\" data-id=\"126860\" src=\"https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/06\/DSC_0231-Medium.jpg\" alt=\"\" class=\"wp-image-126860\" srcset=\"https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/06\/DSC_0231-Medium.jpg 1152w, https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/06\/DSC_0231-Medium-250x167.jpg 250w, https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/06\/DSC_0231-Medium-700x467.jpg 700w, https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/06\/DSC_0231-Medium-768x512.jpg 768w, https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/06\/DSC_0231-Medium-120x80.jpg 120w\" sizes=\"auto, (max-width: 1152px) 100vw, 1152px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-full\"><a href=\"https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/06\/DSC_0236-Medium.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"1152\" height=\"768\" data-id=\"126864\" src=\"https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/06\/DSC_0236-Medium.jpg\" alt=\"\" class=\"wp-image-126864\" srcset=\"https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/06\/DSC_0236-Medium.jpg 1152w, https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/06\/DSC_0236-Medium-250x167.jpg 250w, https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/06\/DSC_0236-Medium-700x467.jpg 700w, https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/06\/DSC_0236-Medium-768x512.jpg 768w, https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/06\/DSC_0236-Medium-120x80.jpg 120w\" sizes=\"auto, (max-width: 1152px) 100vw, 1152px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-full\"><a href=\"https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/06\/DSC_0238-Medium.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"1152\" height=\"768\" data-id=\"126868\" src=\"https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/06\/DSC_0238-Medium.jpg\" alt=\"\" class=\"wp-image-126868\" srcset=\"https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/06\/DSC_0238-Medium.jpg 1152w, https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/06\/DSC_0238-Medium-250x167.jpg 250w, https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/06\/DSC_0238-Medium-700x467.jpg 700w, https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/06\/DSC_0238-Medium-768x512.jpg 768w, https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/06\/DSC_0238-Medium-120x80.jpg 120w\" sizes=\"auto, (max-width: 1152px) 100vw, 1152px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-full\"><a href=\"https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/06\/DSC_0250-Medium.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"1152\" height=\"768\" data-id=\"126872\" src=\"https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/06\/DSC_0250-Medium.jpg\" alt=\"\" class=\"wp-image-126872\" srcset=\"https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/06\/DSC_0250-Medium.jpg 1152w, https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/06\/DSC_0250-Medium-250x167.jpg 250w, https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/06\/DSC_0250-Medium-700x467.jpg 700w, https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/06\/DSC_0250-Medium-768x512.jpg 768w, https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/06\/DSC_0250-Medium-120x80.jpg 120w\" sizes=\"auto, (max-width: 1152px) 100vw, 1152px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-full\"><a href=\"https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/06\/DSC_0251-Medium.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"1152\" height=\"768\" data-id=\"126876\" src=\"https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/06\/DSC_0251-Medium.jpg\" alt=\"\" class=\"wp-image-126876\" srcset=\"https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/06\/DSC_0251-Medium.jpg 1152w, https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/06\/DSC_0251-Medium-250x167.jpg 250w, https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/06\/DSC_0251-Medium-700x467.jpg 700w, https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/06\/DSC_0251-Medium-768x512.jpg 768w, https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/06\/DSC_0251-Medium-120x80.jpg 120w\" sizes=\"auto, (max-width: 1152px) 100vw, 1152px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-full\"><a href=\"https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/06\/DSC_0253-Medium.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"1152\" height=\"768\" data-id=\"126880\" src=\"https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/06\/DSC_0253-Medium.jpg\" alt=\"\" class=\"wp-image-126880\" srcset=\"https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/06\/DSC_0253-Medium.jpg 1152w, https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/06\/DSC_0253-Medium-250x167.jpg 250w, https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/06\/DSC_0253-Medium-700x467.jpg 700w, https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/06\/DSC_0253-Medium-768x512.jpg 768w, https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/06\/DSC_0253-Medium-120x80.jpg 120w\" sizes=\"auto, (max-width: 1152px) 100vw, 1152px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-full\"><a href=\"https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/06\/DSC_0257-Medium.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"1152\" height=\"768\" data-id=\"126884\" src=\"https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/06\/DSC_0257-Medium.jpg\" alt=\"\" class=\"wp-image-126884\" srcset=\"https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/06\/DSC_0257-Medium.jpg 1152w, https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/06\/DSC_0257-Medium-250x167.jpg 250w, https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/06\/DSC_0257-Medium-700x467.jpg 700w, https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/06\/DSC_0257-Medium-768x512.jpg 768w, https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/06\/DSC_0257-Medium-120x80.jpg 120w\" sizes=\"auto, (max-width: 1152px) 100vw, 1152px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-full\"><a href=\"https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/06\/DSC_0264-Medium.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"1152\" height=\"768\" data-id=\"126888\" src=\"https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/06\/DSC_0264-Medium.jpg\" alt=\"\" class=\"wp-image-126888\" srcset=\"https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/06\/DSC_0264-Medium.jpg 1152w, https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/06\/DSC_0264-Medium-250x167.jpg 250w, https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/06\/DSC_0264-Medium-700x467.jpg 700w, https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/06\/DSC_0264-Medium-768x512.jpg 768w, https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/06\/DSC_0264-Medium-120x80.jpg 120w\" sizes=\"auto, (max-width: 1152px) 100vw, 1152px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-full\"><a href=\"https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/06\/DSC_0270-Medium.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"1152\" height=\"768\" data-id=\"126892\" src=\"https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/06\/DSC_0270-Medium.jpg\" alt=\"\" class=\"wp-image-126892\" srcset=\"https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/06\/DSC_0270-Medium.jpg 1152w, https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/06\/DSC_0270-Medium-250x167.jpg 250w, https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/06\/DSC_0270-Medium-700x467.jpg 700w, https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/06\/DSC_0270-Medium-768x512.jpg 768w, https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/06\/DSC_0270-Medium-120x80.jpg 120w\" sizes=\"auto, (max-width: 1152px) 100vw, 1152px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-full\"><a href=\"https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/06\/DSC_0278-Medium.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"1152\" height=\"768\" data-id=\"126896\" src=\"https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/06\/DSC_0278-Medium.jpg\" alt=\"\" class=\"wp-image-126896\" srcset=\"https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/06\/DSC_0278-Medium.jpg 1152w, https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/06\/DSC_0278-Medium-250x167.jpg 250w, https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/06\/DSC_0278-Medium-700x467.jpg 700w, https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/06\/DSC_0278-Medium-768x512.jpg 768w, https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/06\/DSC_0278-Medium-120x80.jpg 120w\" sizes=\"auto, (max-width: 1152px) 100vw, 1152px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-full\"><a href=\"https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/06\/DSC_0282-Medium.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"1152\" height=\"768\" data-id=\"126900\" src=\"https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/06\/DSC_0282-Medium.jpg\" alt=\"\" class=\"wp-image-126900\" srcset=\"https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/06\/DSC_0282-Medium.jpg 1152w, https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/06\/DSC_0282-Medium-250x167.jpg 250w, https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/06\/DSC_0282-Medium-700x467.jpg 700w, https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/06\/DSC_0282-Medium-768x512.jpg 768w, https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/06\/DSC_0282-Medium-120x80.jpg 120w\" sizes=\"auto, (max-width: 1152px) 100vw, 1152px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-full\"><a href=\"https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/06\/DSC_0287-Medium.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"1152\" height=\"768\" data-id=\"126904\" src=\"https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/06\/DSC_0287-Medium.jpg\" alt=\"\" class=\"wp-image-126904\" srcset=\"https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/06\/DSC_0287-Medium.jpg 1152w, https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/06\/DSC_0287-Medium-250x167.jpg 250w, https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/06\/DSC_0287-Medium-700x467.jpg 700w, https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/06\/DSC_0287-Medium-768x512.jpg 768w, https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/06\/DSC_0287-Medium-120x80.jpg 120w\" sizes=\"auto, (max-width: 1152px) 100vw, 1152px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-full\"><a href=\"https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/06\/DSC_0292-Medium.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"1152\" height=\"768\" data-id=\"126908\" src=\"https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/06\/DSC_0292-Medium.jpg\" alt=\"\" class=\"wp-image-126908\" srcset=\"https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/06\/DSC_0292-Medium.jpg 1152w, https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/06\/DSC_0292-Medium-250x167.jpg 250w, https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/06\/DSC_0292-Medium-700x467.jpg 700w, https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/06\/DSC_0292-Medium-768x512.jpg 768w, https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/06\/DSC_0292-Medium-120x80.jpg 120w\" sizes=\"auto, (max-width: 1152px) 100vw, 1152px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-full\"><a href=\"https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/06\/DSC_0294-Medium.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"1152\" height=\"768\" data-id=\"126912\" src=\"https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/06\/DSC_0294-Medium.jpg\" alt=\"\" class=\"wp-image-126912\" srcset=\"https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/06\/DSC_0294-Medium.jpg 1152w, https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/06\/DSC_0294-Medium-250x167.jpg 250w, https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/06\/DSC_0294-Medium-700x467.jpg 700w, https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/06\/DSC_0294-Medium-768x512.jpg 768w, https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/06\/DSC_0294-Medium-120x80.jpg 120w\" sizes=\"auto, (max-width: 1152px) 100vw, 1152px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-full\"><a href=\"https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/06\/DSC_0295-Medium.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"1152\" height=\"768\" data-id=\"126916\" src=\"https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/06\/DSC_0295-Medium.jpg\" alt=\"\" class=\"wp-image-126916\" srcset=\"https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/06\/DSC_0295-Medium.jpg 1152w, https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/06\/DSC_0295-Medium-250x167.jpg 250w, https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/06\/DSC_0295-Medium-700x467.jpg 700w, https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/06\/DSC_0295-Medium-768x512.jpg 768w, https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/06\/DSC_0295-Medium-120x80.jpg 120w\" sizes=\"auto, (max-width: 1152px) 100vw, 1152px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-full\"><a href=\"https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/06\/DSC_0299-Medium.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"1152\" height=\"768\" data-id=\"126920\" src=\"https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/06\/DSC_0299-Medium.jpg\" alt=\"\" class=\"wp-image-126920\" srcset=\"https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/06\/DSC_0299-Medium.jpg 1152w, https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/06\/DSC_0299-Medium-250x167.jpg 250w, https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/06\/DSC_0299-Medium-700x467.jpg 700w, https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/06\/DSC_0299-Medium-768x512.jpg 768w, https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/06\/DSC_0299-Medium-120x80.jpg 120w\" sizes=\"auto, (max-width: 1152px) 100vw, 1152px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-full\"><a href=\"https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/06\/DSC_0300-Medium.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"1152\" height=\"768\" data-id=\"126924\" src=\"https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/06\/DSC_0300-Medium.jpg\" alt=\"\" class=\"wp-image-126924\" srcset=\"https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/06\/DSC_0300-Medium.jpg 1152w, https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/06\/DSC_0300-Medium-250x167.jpg 250w, https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/06\/DSC_0300-Medium-700x467.jpg 700w, https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/06\/DSC_0300-Medium-768x512.jpg 768w, https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/06\/DSC_0300-Medium-120x80.jpg 120w\" sizes=\"auto, (max-width: 1152px) 100vw, 1152px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-full\"><a href=\"https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/06\/DSC_0315-Medium.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"1152\" height=\"768\" data-id=\"126928\" src=\"https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/06\/DSC_0315-Medium.jpg\" alt=\"\" class=\"wp-image-126928\" srcset=\"https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/06\/DSC_0315-Medium.jpg 1152w, https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/06\/DSC_0315-Medium-250x167.jpg 250w, https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/06\/DSC_0315-Medium-700x467.jpg 700w, https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/06\/DSC_0315-Medium-768x512.jpg 768w, https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/06\/DSC_0315-Medium-120x80.jpg 120w\" sizes=\"auto, (max-width: 1152px) 100vw, 1152px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-full\"><a href=\"https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/06\/DSC_0321-Medium.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"1152\" height=\"768\" data-id=\"126932\" src=\"https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/06\/DSC_0321-Medium.jpg\" alt=\"\" class=\"wp-image-126932\" srcset=\"https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/06\/DSC_0321-Medium.jpg 1152w, https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/06\/DSC_0321-Medium-250x167.jpg 250w, https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/06\/DSC_0321-Medium-700x467.jpg 700w, https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/06\/DSC_0321-Medium-768x512.jpg 768w, https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/06\/DSC_0321-Medium-120x80.jpg 120w\" sizes=\"auto, (max-width: 1152px) 100vw, 1152px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-full\"><a href=\"https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/06\/DSC_0328-Medium.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"1152\" height=\"768\" data-id=\"126936\" src=\"https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/06\/DSC_0328-Medium.jpg\" alt=\"\" class=\"wp-image-126936\" srcset=\"https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/06\/DSC_0328-Medium.jpg 1152w, https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/06\/DSC_0328-Medium-250x167.jpg 250w, https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/06\/DSC_0328-Medium-700x467.jpg 700w, https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/06\/DSC_0328-Medium-768x512.jpg 768w, https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/06\/DSC_0328-Medium-120x80.jpg 120w\" sizes=\"auto, (max-width: 1152px) 100vw, 1152px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-full\"><a href=\"https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/06\/DSC_0346-Medium.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"1152\" height=\"768\" data-id=\"126940\" src=\"https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/06\/DSC_0346-Medium.jpg\" alt=\"\" class=\"wp-image-126940\" srcset=\"https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/06\/DSC_0346-Medium.jpg 1152w, https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/06\/DSC_0346-Medium-250x167.jpg 250w, https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/06\/DSC_0346-Medium-700x467.jpg 700w, https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/06\/DSC_0346-Medium-768x512.jpg 768w, https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/06\/DSC_0346-Medium-120x80.jpg 120w\" sizes=\"auto, (max-width: 1152px) 100vw, 1152px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-full\"><a href=\"https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/06\/DSC_0350-Medium.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"1152\" height=\"768\" data-id=\"126944\" src=\"https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/06\/DSC_0350-Medium.jpg\" alt=\"\" class=\"wp-image-126944\" srcset=\"https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/06\/DSC_0350-Medium.jpg 1152w, https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/06\/DSC_0350-Medium-250x167.jpg 250w, https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/06\/DSC_0350-Medium-700x467.jpg 700w, https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/06\/DSC_0350-Medium-768x512.jpg 768w, https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/06\/DSC_0350-Medium-120x80.jpg 120w\" sizes=\"auto, (max-width: 1152px) 100vw, 1152px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-full\"><a href=\"https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/06\/IMG_5957-Medium.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" data-id=\"126948\" src=\"https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/06\/IMG_5957-Medium.jpg\" alt=\"\" class=\"wp-image-126948\" srcset=\"https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/06\/IMG_5957-Medium.jpg 1024w, https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/06\/IMG_5957-Medium-250x188.jpg 250w, https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/06\/IMG_5957-Medium-700x525.jpg 700w, https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/06\/IMG_5957-Medium-768x576.jpg 768w, https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/06\/IMG_5957-Medium-120x90.jpg 120w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-full\"><a href=\"https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/06\/IMG_5958-Medium.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" data-id=\"126952\" src=\"https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/06\/IMG_5958-Medium.jpg\" alt=\"\" class=\"wp-image-126952\" srcset=\"https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/06\/IMG_5958-Medium.jpg 1024w, https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/06\/IMG_5958-Medium-250x188.jpg 250w, https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/06\/IMG_5958-Medium-700x525.jpg 700w, https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/06\/IMG_5958-Medium-768x576.jpg 768w, https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/06\/IMG_5958-Medium-120x90.jpg 120w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-full\"><a href=\"https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/06\/IMG_5959-Medium.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" data-id=\"126956\" src=\"https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/06\/IMG_5959-Medium.jpg\" alt=\"\" class=\"wp-image-126956\" srcset=\"https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/06\/IMG_5959-Medium.jpg 1024w, https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/06\/IMG_5959-Medium-250x188.jpg 250w, https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/06\/IMG_5959-Medium-700x525.jpg 700w, https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/06\/IMG_5959-Medium-768x576.jpg 768w, https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/06\/IMG_5959-Medium-120x90.jpg 120w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-full\"><a href=\"https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/06\/IMG_5960-Medium.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" data-id=\"126960\" src=\"https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/06\/IMG_5960-Medium.jpg\" alt=\"\" class=\"wp-image-126960\" srcset=\"https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/06\/IMG_5960-Medium.jpg 1024w, https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/06\/IMG_5960-Medium-250x188.jpg 250w, https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/06\/IMG_5960-Medium-700x525.jpg 700w, https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/06\/IMG_5960-Medium-768x576.jpg 768w, https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/06\/IMG_5960-Medium-120x90.jpg 120w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-full\"><a href=\"https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/06\/IMG_5961-Medium.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" data-id=\"126964\" src=\"https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/06\/IMG_5961-Medium.jpg\" alt=\"\" class=\"wp-image-126964\" srcset=\"https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/06\/IMG_5961-Medium.jpg 1024w, https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/06\/IMG_5961-Medium-250x188.jpg 250w, https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/06\/IMG_5961-Medium-700x525.jpg 700w, https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/06\/IMG_5961-Medium-768x576.jpg 768w, https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/06\/IMG_5961-Medium-120x90.jpg 120w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-full\"><a href=\"https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/06\/IMG_5963-Medium.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" data-id=\"126968\" src=\"https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/06\/IMG_5963-Medium.jpg\" alt=\"\" class=\"wp-image-126968\" srcset=\"https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/06\/IMG_5963-Medium.jpg 1024w, https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/06\/IMG_5963-Medium-250x188.jpg 250w, https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/06\/IMG_5963-Medium-700x525.jpg 700w, https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/06\/IMG_5963-Medium-768x576.jpg 768w, https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/06\/IMG_5963-Medium-120x90.jpg 120w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-full\"><a href=\"https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/06\/IMG_5964-Medium.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" data-id=\"126972\" src=\"https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/06\/IMG_5964-Medium.jpg\" alt=\"\" class=\"wp-image-126972\" srcset=\"https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/06\/IMG_5964-Medium.jpg 1024w, https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/06\/IMG_5964-Medium-250x188.jpg 250w, https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/06\/IMG_5964-Medium-700x525.jpg 700w, https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/06\/IMG_5964-Medium-768x576.jpg 768w, https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/06\/IMG_5964-Medium-120x90.jpg 120w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-full\"><a href=\"https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/06\/IMG_5975-Medium.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" data-id=\"126976\" src=\"https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/06\/IMG_5975-Medium.jpg\" alt=\"\" class=\"wp-image-126976\" srcset=\"https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/06\/IMG_5975-Medium.jpg 1024w, https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/06\/IMG_5975-Medium-250x188.jpg 250w, https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/06\/IMG_5975-Medium-700x525.jpg 700w, https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/06\/IMG_5975-Medium-768x576.jpg 768w, https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/06\/IMG_5975-Medium-120x90.jpg 120w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-full\"><a href=\"https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/06\/IMG_5979-Medium.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"1365\" height=\"768\" data-id=\"126980\" src=\"https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/06\/IMG_5979-Medium.jpg\" alt=\"\" class=\"wp-image-126980\" srcset=\"https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/06\/IMG_5979-Medium.jpg 1365w, https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/06\/IMG_5979-Medium-250x141.jpg 250w, https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/06\/IMG_5979-Medium-700x394.jpg 700w, https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/06\/IMG_5979-Medium-768x432.jpg 768w, https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/06\/IMG_5979-Medium-120x68.jpg 120w\" sizes=\"auto, (max-width: 1365px) 100vw, 1365px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-full\"><a href=\"https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/06\/IMG_6006-Medium.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"1365\" height=\"768\" data-id=\"126984\" src=\"https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/06\/IMG_6006-Medium.jpg\" alt=\"\" class=\"wp-image-126984\" srcset=\"https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/06\/IMG_6006-Medium.jpg 1365w, https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/06\/IMG_6006-Medium-250x141.jpg 250w, https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/06\/IMG_6006-Medium-700x394.jpg 700w, https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/06\/IMG_6006-Medium-768x432.jpg 768w, https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/06\/IMG_6006-Medium-120x68.jpg 120w\" sizes=\"auto, (max-width: 1365px) 100vw, 1365px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-full\"><a href=\"https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/06\/IMG_6007-Medium.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"1365\" height=\"768\" data-id=\"126988\" src=\"https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/06\/IMG_6007-Medium.jpg\" alt=\"\" class=\"wp-image-126988\" srcset=\"https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/06\/IMG_6007-Medium.jpg 1365w, https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/06\/IMG_6007-Medium-250x141.jpg 250w, https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/06\/IMG_6007-Medium-700x394.jpg 700w, https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/06\/IMG_6007-Medium-768x432.jpg 768w, https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/06\/IMG_6007-Medium-120x68.jpg 120w\" sizes=\"auto, (max-width: 1365px) 100vw, 1365px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-full\"><a href=\"https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/06\/PHOTO-2024-06-10-10-53-30-Medium.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"781\" height=\"768\" data-id=\"126992\" src=\"https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/06\/PHOTO-2024-06-10-10-53-30-Medium.jpg\" alt=\"\" class=\"wp-image-126992\" srcset=\"https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/06\/PHOTO-2024-06-10-10-53-30-Medium.jpg 781w, https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/06\/PHOTO-2024-06-10-10-53-30-Medium-250x246.jpg 250w, https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/06\/PHOTO-2024-06-10-10-53-30-Medium-700x688.jpg 700w, https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/06\/PHOTO-2024-06-10-10-53-30-Medium-768x755.jpg 768w, https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/06\/PHOTO-2024-06-10-10-53-30-Medium-120x118.jpg 120w\" sizes=\"auto, (max-width: 781px) 100vw, 781px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-full\"><a href=\"https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/06\/PHOTO-2024-06-10-10-53-30-2-Medium.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"792\" height=\"768\" data-id=\"126996\" src=\"https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/06\/PHOTO-2024-06-10-10-53-30-2-Medium.jpg\" alt=\"\" class=\"wp-image-126996\" srcset=\"https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/06\/PHOTO-2024-06-10-10-53-30-2-Medium.jpg 792w, https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/06\/PHOTO-2024-06-10-10-53-30-2-Medium-250x242.jpg 250w, https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/06\/PHOTO-2024-06-10-10-53-30-2-Medium-700x679.jpg 700w, https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/06\/PHOTO-2024-06-10-10-53-30-2-Medium-768x745.jpg 768w, https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/06\/PHOTO-2024-06-10-10-53-30-2-Medium-120x116.jpg 120w\" sizes=\"auto, (max-width: 792px) 100vw, 792px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-full\"><a href=\"https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/06\/PHOTO-2024-06-10-10-54-23-Medium.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"889\" height=\"768\" data-id=\"127000\" src=\"https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/06\/PHOTO-2024-06-10-10-54-23-Medium.jpg\" alt=\"\" class=\"wp-image-127000\" srcset=\"https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/06\/PHOTO-2024-06-10-10-54-23-Medium.jpg 889w, https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/06\/PHOTO-2024-06-10-10-54-23-Medium-250x216.jpg 250w, https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/06\/PHOTO-2024-06-10-10-54-23-Medium-700x605.jpg 700w, https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/06\/PHOTO-2024-06-10-10-54-23-Medium-768x663.jpg 768w, https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/06\/PHOTO-2024-06-10-10-54-23-Medium-120x104.jpg 120w\" sizes=\"auto, (max-width: 889px) 100vw, 889px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-full\"><a href=\"https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/06\/PHOTO-2024-06-10-10-54-24-Medium.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"1000\" height=\"768\" data-id=\"127004\" src=\"https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/06\/PHOTO-2024-06-10-10-54-24-Medium.jpg\" alt=\"\" class=\"wp-image-127004\" srcset=\"https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/06\/PHOTO-2024-06-10-10-54-24-Medium.jpg 1000w, https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/06\/PHOTO-2024-06-10-10-54-24-Medium-250x192.jpg 250w, https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/06\/PHOTO-2024-06-10-10-54-24-Medium-700x538.jpg 700w, https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/06\/PHOTO-2024-06-10-10-54-24-Medium-768x590.jpg 768w, https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/06\/PHOTO-2024-06-10-10-54-24-Medium-120x92.jpg 120w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-full\"><a href=\"https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/06\/PHOTO-2024-06-10-10-54-24-2-Medium.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"902\" height=\"768\" data-id=\"127008\" src=\"https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/06\/PHOTO-2024-06-10-10-54-24-2-Medium.jpg\" alt=\"\" class=\"wp-image-127008\" srcset=\"https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/06\/PHOTO-2024-06-10-10-54-24-2-Medium.jpg 902w, https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/06\/PHOTO-2024-06-10-10-54-24-2-Medium-250x213.jpg 250w, https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/06\/PHOTO-2024-06-10-10-54-24-2-Medium-700x596.jpg 700w, https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/06\/PHOTO-2024-06-10-10-54-24-2-Medium-768x654.jpg 768w, https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/06\/PHOTO-2024-06-10-10-54-24-2-Medium-120x102.jpg 120w\" sizes=\"auto, (max-width: 902px) 100vw, 902px\" \/><\/a><\/figure>\n<\/figure>\n","protected":false},"excerpt":{"rendered":"F\u00e9licitations \u00e0 toute la promotion du Baccalaur\u00e9at 2024 ! ","protected":false},"author":1,"featured_media":126944,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"rs_blank_template":"","rs_page_bg_color":"","slide_template_v7":"","footnotes":"","_links_to":"","_links_to_target":""},"categories":[10,1],"tags":[],"class_list":["post-126645","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-generales","category-non-classifiee"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>C\u00e9r\u00e9monie de Remise des Dipl\u00f4mes 2024 - Lyc\u00e9e International Barcelona \u00b7 Bon Soleil<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/bonsoleil.es\/es\/ceremonie-de-remise-des-diplomes-2024\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"C\u00e9r\u00e9monie de Remise des Dipl\u00f4mes 2024 - Lyc\u00e9e International Barcelona \u00b7 Bon Soleil\" \/>\n<meta property=\"og:description\" content=\"F\u00e9licitations \u00e0 toute la promotion du Baccalaur\u00e9at 2024 !\" \/>\n<meta property=\"og:url\" content=\"https:\/\/bonsoleil.es\/es\/ceremonie-de-remise-des-diplomes-2024\/\" \/>\n<meta property=\"og:site_name\" content=\"Lyc\u00e9e International Barcelona \u00b7 Bon Soleil\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/libBonSoleil\/\" \/>\n<meta property=\"article:published_time\" content=\"2024-06-11T07:34:43+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-06-11T07:37:49+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/06\/DSC_0350-Medium.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1152\" \/>\n\t<meta property=\"og:image:height\" content=\"768\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"libbs\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@lib_bonsoleil\" \/>\n<meta name=\"twitter:site\" content=\"@lib_bonsoleil\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"libbs\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"20 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/bonsoleil.es\\\/es\\\/ceremonie-de-remise-des-diplomes-2024\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/bonsoleil.es\\\/es\\\/ceremonie-de-remise-des-diplomes-2024\\\/\"},\"author\":{\"name\":\"libbs\",\"@id\":\"https:\\\/\\\/bonsoleil.es\\\/es\\\/#\\\/schema\\\/person\\\/f90f9175af4fad9c626fd2873bc546ec\"},\"headline\":\"C\u00e9r\u00e9monie de Remise des Dipl\u00f4mes 2024\",\"datePublished\":\"2024-06-11T07:34:43+00:00\",\"dateModified\":\"2024-06-11T07:37:49+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/bonsoleil.es\\\/es\\\/ceremonie-de-remise-des-diplomes-2024\\\/\"},\"wordCount\":166,\"image\":{\"@id\":\"https:\\\/\\\/bonsoleil.es\\\/es\\\/ceremonie-de-remise-des-diplomes-2024\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/bonsoleil.es\\\/web\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/DSC_0350-Medium.jpg\",\"articleSection\":[\"G\u00e9n\u00e9rales\",\"Non classifi\u00e9(e)\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/bonsoleil.es\\\/es\\\/ceremonie-de-remise-des-diplomes-2024\\\/\",\"url\":\"https:\\\/\\\/bonsoleil.es\\\/es\\\/ceremonie-de-remise-des-diplomes-2024\\\/\",\"name\":\"C\u00e9r\u00e9monie de Remise des Dipl\u00f4mes 2024 - Lyc\u00e9e International Barcelona \u00b7 Bon Soleil\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/bonsoleil.es\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/bonsoleil.es\\\/es\\\/ceremonie-de-remise-des-diplomes-2024\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/bonsoleil.es\\\/es\\\/ceremonie-de-remise-des-diplomes-2024\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/bonsoleil.es\\\/web\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/DSC_0350-Medium.jpg\",\"datePublished\":\"2024-06-11T07:34:43+00:00\",\"dateModified\":\"2024-06-11T07:37:49+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/bonsoleil.es\\\/es\\\/#\\\/schema\\\/person\\\/f90f9175af4fad9c626fd2873bc546ec\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/bonsoleil.es\\\/es\\\/ceremonie-de-remise-des-diplomes-2024\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/bonsoleil.es\\\/es\\\/ceremonie-de-remise-des-diplomes-2024\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/bonsoleil.es\\\/es\\\/ceremonie-de-remise-des-diplomes-2024\\\/#primaryimage\",\"url\":\"https:\\\/\\\/bonsoleil.es\\\/web\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/DSC_0350-Medium.jpg\",\"contentUrl\":\"https:\\\/\\\/bonsoleil.es\\\/web\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/DSC_0350-Medium.jpg\",\"width\":1152,\"height\":768},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/bonsoleil.es\\\/es\\\/ceremonie-de-remise-des-diplomes-2024\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/bonsoleil.es\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"C\u00e9r\u00e9monie de Remise des Dipl\u00f4mes 2024\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/bonsoleil.es\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/bonsoleil.es\\\/es\\\/\",\"name\":\"Lyc\u00e9e International Barcelona \u00b7 Bon Soleil\",\"description\":\"Lyc\u00e9e International Barcelona\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/bonsoleil.es\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/bonsoleil.es\\\/es\\\/#\\\/schema\\\/person\\\/f90f9175af4fad9c626fd2873bc546ec\",\"name\":\"libbs\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/bonsoleil.es\\\/web\\\/wp-content\\\/litespeed\\\/avatar\\\/6719caedb5831fa7538835120a8121f8.jpg?ver=1783691672\",\"url\":\"https:\\\/\\\/bonsoleil.es\\\/web\\\/wp-content\\\/litespeed\\\/avatar\\\/6719caedb5831fa7538835120a8121f8.jpg?ver=1783691672\",\"contentUrl\":\"https:\\\/\\\/bonsoleil.es\\\/web\\\/wp-content\\\/litespeed\\\/avatar\\\/6719caedb5831fa7538835120a8121f8.jpg?ver=1783691672\",\"caption\":\"libbs\"},\"sameAs\":[\"http:\\\/\\\/localhost\\\/bonsoleil\\\/new_web\"],\"url\":\"https:\\\/\\\/bonsoleil.es\\\/es\\\/author\\\/libbs\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"C\u00e9r\u00e9monie de Remise des Dipl\u00f4mes 2024 - Lyc\u00e9e International Barcelona \u00b7 Bon Soleil","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/bonsoleil.es\/es\/ceremonie-de-remise-des-diplomes-2024\/","og_locale":"es_ES","og_type":"article","og_title":"C\u00e9r\u00e9monie de Remise des Dipl\u00f4mes 2024 - Lyc\u00e9e International Barcelona \u00b7 Bon Soleil","og_description":"F\u00e9licitations \u00e0 toute la promotion du Baccalaur\u00e9at 2024 !","og_url":"https:\/\/bonsoleil.es\/es\/ceremonie-de-remise-des-diplomes-2024\/","og_site_name":"Lyc\u00e9e International Barcelona \u00b7 Bon Soleil","article_publisher":"https:\/\/www.facebook.com\/libBonSoleil\/","article_published_time":"2024-06-11T07:34:43+00:00","article_modified_time":"2024-06-11T07:37:49+00:00","og_image":[{"width":1152,"height":768,"url":"https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/06\/DSC_0350-Medium.jpg","type":"image\/jpeg"}],"author":"libbs","twitter_card":"summary_large_image","twitter_creator":"@lib_bonsoleil","twitter_site":"@lib_bonsoleil","twitter_misc":{"Escrito por":"libbs","Tiempo de lectura":"20 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/bonsoleil.es\/es\/ceremonie-de-remise-des-diplomes-2024\/#article","isPartOf":{"@id":"https:\/\/bonsoleil.es\/es\/ceremonie-de-remise-des-diplomes-2024\/"},"author":{"name":"libbs","@id":"https:\/\/bonsoleil.es\/es\/#\/schema\/person\/f90f9175af4fad9c626fd2873bc546ec"},"headline":"C\u00e9r\u00e9monie de Remise des Dipl\u00f4mes 2024","datePublished":"2024-06-11T07:34:43+00:00","dateModified":"2024-06-11T07:37:49+00:00","mainEntityOfPage":{"@id":"https:\/\/bonsoleil.es\/es\/ceremonie-de-remise-des-diplomes-2024\/"},"wordCount":166,"image":{"@id":"https:\/\/bonsoleil.es\/es\/ceremonie-de-remise-des-diplomes-2024\/#primaryimage"},"thumbnailUrl":"https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/06\/DSC_0350-Medium.jpg","articleSection":["G\u00e9n\u00e9rales","Non classifi\u00e9(e)"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/bonsoleil.es\/es\/ceremonie-de-remise-des-diplomes-2024\/","url":"https:\/\/bonsoleil.es\/es\/ceremonie-de-remise-des-diplomes-2024\/","name":"C\u00e9r\u00e9monie de Remise des Dipl\u00f4mes 2024 - Lyc\u00e9e International Barcelona \u00b7 Bon Soleil","isPartOf":{"@id":"https:\/\/bonsoleil.es\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/bonsoleil.es\/es\/ceremonie-de-remise-des-diplomes-2024\/#primaryimage"},"image":{"@id":"https:\/\/bonsoleil.es\/es\/ceremonie-de-remise-des-diplomes-2024\/#primaryimage"},"thumbnailUrl":"https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/06\/DSC_0350-Medium.jpg","datePublished":"2024-06-11T07:34:43+00:00","dateModified":"2024-06-11T07:37:49+00:00","author":{"@id":"https:\/\/bonsoleil.es\/es\/#\/schema\/person\/f90f9175af4fad9c626fd2873bc546ec"},"breadcrumb":{"@id":"https:\/\/bonsoleil.es\/es\/ceremonie-de-remise-des-diplomes-2024\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/bonsoleil.es\/es\/ceremonie-de-remise-des-diplomes-2024\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/bonsoleil.es\/es\/ceremonie-de-remise-des-diplomes-2024\/#primaryimage","url":"https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/06\/DSC_0350-Medium.jpg","contentUrl":"https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/06\/DSC_0350-Medium.jpg","width":1152,"height":768},{"@type":"BreadcrumbList","@id":"https:\/\/bonsoleil.es\/es\/ceremonie-de-remise-des-diplomes-2024\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/bonsoleil.es\/es\/"},{"@type":"ListItem","position":2,"name":"C\u00e9r\u00e9monie de Remise des Dipl\u00f4mes 2024"}]},{"@type":"WebSite","@id":"https:\/\/bonsoleil.es\/es\/#website","url":"https:\/\/bonsoleil.es\/es\/","name":"Lyc\u00e9e International Barcelona \u00b7 Bon Soleil","description":"Lyc\u00e9e International Barcelona","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/bonsoleil.es\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/bonsoleil.es\/es\/#\/schema\/person\/f90f9175af4fad9c626fd2873bc546ec","name":"libbs","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/bonsoleil.es\/web\/wp-content\/litespeed\/avatar\/6719caedb5831fa7538835120a8121f8.jpg?ver=1783691672","url":"https:\/\/bonsoleil.es\/web\/wp-content\/litespeed\/avatar\/6719caedb5831fa7538835120a8121f8.jpg?ver=1783691672","contentUrl":"https:\/\/bonsoleil.es\/web\/wp-content\/litespeed\/avatar\/6719caedb5831fa7538835120a8121f8.jpg?ver=1783691672","caption":"libbs"},"sameAs":["http:\/\/localhost\/bonsoleil\/new_web"],"url":"https:\/\/bonsoleil.es\/es\/author\/libbs\/"}]}},"_links":{"self":[{"href":"https:\/\/bonsoleil.es\/es\/wp-json\/wp\/v2\/posts\/126645","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/bonsoleil.es\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/bonsoleil.es\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/bonsoleil.es\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/bonsoleil.es\/es\/wp-json\/wp\/v2\/comments?post=126645"}],"version-history":[{"count":2,"href":"https:\/\/bonsoleil.es\/es\/wp-json\/wp\/v2\/posts\/126645\/revisions"}],"predecessor-version":[{"id":127013,"href":"https:\/\/bonsoleil.es\/es\/wp-json\/wp\/v2\/posts\/126645\/revisions\/127013"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/bonsoleil.es\/es\/wp-json\/wp\/v2\/media\/126944"}],"wp:attachment":[{"href":"https:\/\/bonsoleil.es\/es\/wp-json\/wp\/v2\/media?parent=126645"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/bonsoleil.es\/es\/wp-json\/wp\/v2\/categories?post=126645"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/bonsoleil.es\/es\/wp-json\/wp\/v2\/tags?post=126645"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}