{"id":133377,"date":"2024-10-08T09:34:41","date_gmt":"2024-10-08T07:34:41","guid":{"rendered":"https:\/\/bonsoleil.es\/?p=133377"},"modified":"2024-10-08T09:34:42","modified_gmt":"2024-10-08T07:34:42","slug":"alumnos-por-el-mundo-4","status":"publish","type":"post","link":"https:\/\/bonsoleil.es\/es\/alumnos-por-el-mundo-4\/","title":{"rendered":"Alumnos por el mundo"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">\u00bfD\u00f3nde se fue el tiempo? Lo pienso ahora, despu\u00e9s de graduarme\u2026 \u00a1qu\u00e9 r\u00e1pido se me han pasado mis 12 a\u00f1os en Bon Soleil! Esos a\u00f1os en esta escuela guardan muchos recuerdos que recordar\u00e9 toda mi vida. Bon Soleil me ha preparado para afrontar esta nueva etapa: la universidad.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Quiero destacar la gran ayuda que recib\u00ed de mis profesores, quienes me apoyaron hasta el final para lograr mi meta. Gracias a su dedicaci\u00f3n y voluntad constante, he llegado a donde estoy ahora. Estoy muy contenta con mi universidad, la University of Western Ontario en Canad\u00e1, aunque parte de m\u00ed echa de menos a mis amigos y profesores de Bon Soleil.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Gracias, Bon Soleil, por haberme preparado durante tantos a\u00f1os y por haber hecho mis sue\u00f1os realidad.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Alexandra A.<br>Promoci\u00f3n 2023-24<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u2026<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">O\u00f9 est pass\u00e9 le temps ? C\u2019est ce que je me dis maintenant, apr\u00e8s avoir apr\u00e8s avoir termin\u00e9 mes \u00e9tudes&#8230; Ces 12 ann\u00e9es \u00e0 Bon Soleil sont pass\u00e9es si vite ! Ces ann\u00e9es dans cette \u00e9cole sont remplies de souvenirs que je garderai toute ma vie. Bon Soleil m\u2019a pr\u00e9par\u00e9e \u00e0 affronter cette nouvelle \u00e9tape : l\u2019universit\u00e9.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Je tiens \u00e0 souligner le grand soutien que j\u2019ai re\u00e7u de mes professeurs, qui m\u2019ont accompagn\u00e9e jusqu\u2019au bout pour atteindre mon objectif. Gr\u00e2ce \u00e0 leur d\u00e9vouement et \u00e0 leur volont\u00e9 constante, j\u2019en suis l\u00e0 o\u00f9 je suis aujourd\u2019hui. Je suis tr\u00e8s heureuse d\u2019\u00eatre \u00e0 la University of Western Ontario au Canada, m\u00eame si une partie de moi ressent la nostalgie de mes amis et professeurs de Bon Soleil.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Merci, Bon Soleil, de m\u2019avoir pr\u00e9par\u00e9e pendant toutes ces ann\u00e9es et d\u2019avoir r\u00e9alis\u00e9 mes r\u00eaves.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Alexandra A.<br>Promotion 2023-24<\/p>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-1 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"700\" height=\"700\" data-id=\"133378\" src=\"https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/10\/1-1-700x700.jpg\" alt=\"\" class=\"wp-image-133378\" srcset=\"https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/10\/1-1-700x700.jpg 700w, https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/10\/1-1-250x250.jpg 250w, https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/10\/1-1-150x150.jpg 150w, https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/10\/1-1-768x768.jpg 768w, https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/10\/1-1-120x120.jpg 120w, https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/10\/1-1.jpg 1080w\" sizes=\"auto, (max-width: 700px) 100vw, 700px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"700\" height=\"700\" data-id=\"133382\" src=\"https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/10\/2-1-700x700.jpg\" alt=\"\" class=\"wp-image-133382\" srcset=\"https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/10\/2-1-700x700.jpg 700w, https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/10\/2-1-250x250.jpg 250w, https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/10\/2-1-150x150.jpg 150w, https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/10\/2-1-768x768.jpg 768w, https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/10\/2-1-120x120.jpg 120w, https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/10\/2-1.jpg 1080w\" sizes=\"auto, (max-width: 700px) 100vw, 700px\" \/><\/figure>\n<\/figure>\n","protected":false},"excerpt":{"rendered":"\u00bfD\u00f3nde se fue el tiempo? Lo pienso ahora, despu\u00e9s de graduarme\u2026 \u00a1qu\u00e9 r\u00e1pido se me han pasado mis 12 a\u00f1os en Bon Soleil! ","protected":false},"author":1,"featured_media":133378,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"rs_blank_template":"","rs_page_bg_color":"","slide_template_v7":"","footnotes":"","_links_to":"","_links_to_target":""},"categories":[1],"tags":[],"class_list":["post-133377","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-non-classifiee"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Alumnos por el mundo - Lyc\u00e9e International Barcelona \u00b7 Bon Soleil<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/bonsoleil.es\/es\/alumnos-por-el-mundo-4\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Alumnos por el mundo - Lyc\u00e9e International Barcelona \u00b7 Bon Soleil\" \/>\n<meta property=\"og:description\" content=\"\u00bfD\u00f3nde se fue el tiempo? Lo pienso ahora, despu\u00e9s de graduarme\u2026 \u00a1qu\u00e9 r\u00e1pido se me han pasado mis 12 a\u00f1os en Bon Soleil!\" \/>\n<meta property=\"og:url\" content=\"https:\/\/bonsoleil.es\/es\/alumnos-por-el-mundo-4\/\" \/>\n<meta property=\"og:site_name\" content=\"Lyc\u00e9e International Barcelona \u00b7 Bon Soleil\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/libBonSoleil\/\" \/>\n<meta property=\"article:published_time\" content=\"2024-10-08T07:34:41+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-10-08T07:34:42+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/10\/1-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1080\" \/>\n\t<meta property=\"og:image:height\" content=\"1080\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"libbs\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@lib_bonsoleil\" \/>\n<meta name=\"twitter:site\" content=\"@lib_bonsoleil\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"libbs\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/bonsoleil.es\\\/es\\\/alumnos-por-el-mundo-4\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/bonsoleil.es\\\/es\\\/alumnos-por-el-mundo-4\\\/\"},\"author\":{\"name\":\"libbs\",\"@id\":\"https:\\\/\\\/bonsoleil.es\\\/es\\\/#\\\/schema\\\/person\\\/f90f9175af4fad9c626fd2873bc546ec\"},\"headline\":\"Alumnos por el mundo\",\"datePublished\":\"2024-10-08T07:34:41+00:00\",\"dateModified\":\"2024-10-08T07:34:42+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/bonsoleil.es\\\/es\\\/alumnos-por-el-mundo-4\\\/\"},\"wordCount\":304,\"image\":{\"@id\":\"https:\\\/\\\/bonsoleil.es\\\/es\\\/alumnos-por-el-mundo-4\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/bonsoleil.es\\\/web\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/1-1.jpg\",\"articleSection\":[\"Non classifi\u00e9(e)\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/bonsoleil.es\\\/es\\\/alumnos-por-el-mundo-4\\\/\",\"url\":\"https:\\\/\\\/bonsoleil.es\\\/es\\\/alumnos-por-el-mundo-4\\\/\",\"name\":\"Alumnos por el mundo - Lyc\u00e9e International Barcelona \u00b7 Bon Soleil\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/bonsoleil.es\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/bonsoleil.es\\\/es\\\/alumnos-por-el-mundo-4\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/bonsoleil.es\\\/es\\\/alumnos-por-el-mundo-4\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/bonsoleil.es\\\/web\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/1-1.jpg\",\"datePublished\":\"2024-10-08T07:34:41+00:00\",\"dateModified\":\"2024-10-08T07:34:42+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/bonsoleil.es\\\/es\\\/#\\\/schema\\\/person\\\/f90f9175af4fad9c626fd2873bc546ec\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/bonsoleil.es\\\/es\\\/alumnos-por-el-mundo-4\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/bonsoleil.es\\\/es\\\/alumnos-por-el-mundo-4\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/bonsoleil.es\\\/es\\\/alumnos-por-el-mundo-4\\\/#primaryimage\",\"url\":\"https:\\\/\\\/bonsoleil.es\\\/web\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/1-1.jpg\",\"contentUrl\":\"https:\\\/\\\/bonsoleil.es\\\/web\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/1-1.jpg\",\"width\":1080,\"height\":1080},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/bonsoleil.es\\\/es\\\/alumnos-por-el-mundo-4\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/bonsoleil.es\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Alumnos por el mundo\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/bonsoleil.es\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/bonsoleil.es\\\/es\\\/\",\"name\":\"Lyc\u00e9e International Barcelona \u00b7 Bon Soleil\",\"description\":\"Lyc\u00e9e International Barcelona\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/bonsoleil.es\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/bonsoleil.es\\\/es\\\/#\\\/schema\\\/person\\\/f90f9175af4fad9c626fd2873bc546ec\",\"name\":\"libbs\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/bonsoleil.es\\\/web\\\/wp-content\\\/litespeed\\\/avatar\\\/6719caedb5831fa7538835120a8121f8.jpg?ver=1783691672\",\"url\":\"https:\\\/\\\/bonsoleil.es\\\/web\\\/wp-content\\\/litespeed\\\/avatar\\\/6719caedb5831fa7538835120a8121f8.jpg?ver=1783691672\",\"contentUrl\":\"https:\\\/\\\/bonsoleil.es\\\/web\\\/wp-content\\\/litespeed\\\/avatar\\\/6719caedb5831fa7538835120a8121f8.jpg?ver=1783691672\",\"caption\":\"libbs\"},\"sameAs\":[\"http:\\\/\\\/localhost\\\/bonsoleil\\\/new_web\"],\"url\":\"https:\\\/\\\/bonsoleil.es\\\/es\\\/author\\\/libbs\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Alumnos por el mundo - Lyc\u00e9e International Barcelona \u00b7 Bon Soleil","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/bonsoleil.es\/es\/alumnos-por-el-mundo-4\/","og_locale":"es_ES","og_type":"article","og_title":"Alumnos por el mundo - Lyc\u00e9e International Barcelona \u00b7 Bon Soleil","og_description":"\u00bfD\u00f3nde se fue el tiempo? Lo pienso ahora, despu\u00e9s de graduarme\u2026 \u00a1qu\u00e9 r\u00e1pido se me han pasado mis 12 a\u00f1os en Bon Soleil!","og_url":"https:\/\/bonsoleil.es\/es\/alumnos-por-el-mundo-4\/","og_site_name":"Lyc\u00e9e International Barcelona \u00b7 Bon Soleil","article_publisher":"https:\/\/www.facebook.com\/libBonSoleil\/","article_published_time":"2024-10-08T07:34:41+00:00","article_modified_time":"2024-10-08T07:34:42+00:00","og_image":[{"width":1080,"height":1080,"url":"https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/10\/1-1.jpg","type":"image\/jpeg"}],"author":"libbs","twitter_card":"summary_large_image","twitter_creator":"@lib_bonsoleil","twitter_site":"@lib_bonsoleil","twitter_misc":{"Escrito por":"libbs","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/bonsoleil.es\/es\/alumnos-por-el-mundo-4\/#article","isPartOf":{"@id":"https:\/\/bonsoleil.es\/es\/alumnos-por-el-mundo-4\/"},"author":{"name":"libbs","@id":"https:\/\/bonsoleil.es\/es\/#\/schema\/person\/f90f9175af4fad9c626fd2873bc546ec"},"headline":"Alumnos por el mundo","datePublished":"2024-10-08T07:34:41+00:00","dateModified":"2024-10-08T07:34:42+00:00","mainEntityOfPage":{"@id":"https:\/\/bonsoleil.es\/es\/alumnos-por-el-mundo-4\/"},"wordCount":304,"image":{"@id":"https:\/\/bonsoleil.es\/es\/alumnos-por-el-mundo-4\/#primaryimage"},"thumbnailUrl":"https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/10\/1-1.jpg","articleSection":["Non classifi\u00e9(e)"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/bonsoleil.es\/es\/alumnos-por-el-mundo-4\/","url":"https:\/\/bonsoleil.es\/es\/alumnos-por-el-mundo-4\/","name":"Alumnos por el mundo - Lyc\u00e9e International Barcelona \u00b7 Bon Soleil","isPartOf":{"@id":"https:\/\/bonsoleil.es\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/bonsoleil.es\/es\/alumnos-por-el-mundo-4\/#primaryimage"},"image":{"@id":"https:\/\/bonsoleil.es\/es\/alumnos-por-el-mundo-4\/#primaryimage"},"thumbnailUrl":"https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/10\/1-1.jpg","datePublished":"2024-10-08T07:34:41+00:00","dateModified":"2024-10-08T07:34:42+00:00","author":{"@id":"https:\/\/bonsoleil.es\/es\/#\/schema\/person\/f90f9175af4fad9c626fd2873bc546ec"},"breadcrumb":{"@id":"https:\/\/bonsoleil.es\/es\/alumnos-por-el-mundo-4\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/bonsoleil.es\/es\/alumnos-por-el-mundo-4\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/bonsoleil.es\/es\/alumnos-por-el-mundo-4\/#primaryimage","url":"https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/10\/1-1.jpg","contentUrl":"https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/10\/1-1.jpg","width":1080,"height":1080},{"@type":"BreadcrumbList","@id":"https:\/\/bonsoleil.es\/es\/alumnos-por-el-mundo-4\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/bonsoleil.es\/es\/"},{"@type":"ListItem","position":2,"name":"Alumnos por el mundo"}]},{"@type":"WebSite","@id":"https:\/\/bonsoleil.es\/es\/#website","url":"https:\/\/bonsoleil.es\/es\/","name":"Lyc\u00e9e International Barcelona \u00b7 Bon Soleil","description":"Lyc\u00e9e International Barcelona","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/bonsoleil.es\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/bonsoleil.es\/es\/#\/schema\/person\/f90f9175af4fad9c626fd2873bc546ec","name":"libbs","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/bonsoleil.es\/web\/wp-content\/litespeed\/avatar\/6719caedb5831fa7538835120a8121f8.jpg?ver=1783691672","url":"https:\/\/bonsoleil.es\/web\/wp-content\/litespeed\/avatar\/6719caedb5831fa7538835120a8121f8.jpg?ver=1783691672","contentUrl":"https:\/\/bonsoleil.es\/web\/wp-content\/litespeed\/avatar\/6719caedb5831fa7538835120a8121f8.jpg?ver=1783691672","caption":"libbs"},"sameAs":["http:\/\/localhost\/bonsoleil\/new_web"],"url":"https:\/\/bonsoleil.es\/es\/author\/libbs\/"}]}},"_links":{"self":[{"href":"https:\/\/bonsoleil.es\/es\/wp-json\/wp\/v2\/posts\/133377","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/bonsoleil.es\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/bonsoleil.es\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/bonsoleil.es\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/bonsoleil.es\/es\/wp-json\/wp\/v2\/comments?post=133377"}],"version-history":[{"count":1,"href":"https:\/\/bonsoleil.es\/es\/wp-json\/wp\/v2\/posts\/133377\/revisions"}],"predecessor-version":[{"id":133386,"href":"https:\/\/bonsoleil.es\/es\/wp-json\/wp\/v2\/posts\/133377\/revisions\/133386"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/bonsoleil.es\/es\/wp-json\/wp\/v2\/media\/133378"}],"wp:attachment":[{"href":"https:\/\/bonsoleil.es\/es\/wp-json\/wp\/v2\/media?parent=133377"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/bonsoleil.es\/es\/wp-json\/wp\/v2\/categories?post=133377"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/bonsoleil.es\/es\/wp-json\/wp\/v2\/tags?post=133377"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}