{"id":134058,"date":"2024-10-22T09:18:43","date_gmt":"2024-10-22T07:18:43","guid":{"rendered":"https:\/\/bonsoleil.es\/?p=134058"},"modified":"2024-11-13T09:26:16","modified_gmt":"2024-11-13T08:26:16","slug":"barcelona-activa-porta-22","status":"publish","type":"post","link":"https:\/\/bonsoleil.es\/es\/barcelona-activa-porta-22\/","title":{"rendered":"Barcelona Activa Porta 22@"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Les \u00e9l\u00e8ves de 2nde ont particip\u00e9 \u00e0 leur premier atelier d\u2019orientation professionnelle \u00e0 \u00ab Barcelona Activa Porta 22 \u00bb ! Les jeunes ont eu l\u2019occasion d&#8217;amorcer une r\u00e9flexion sur les possibles professions qu\u2019ils envisagent \u00e0 partir d\u2019un test qui met en valeur \u00e9galement leurs affinit\u00e9s. D\u00e9marche \u00e0 suivre!<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">&#8230;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Los alumnos de 2nde han participado en su primer taller de orientaci\u00f3n profesional en \u00abBarcelona Activa Porta 22\u00bb. Los j\u00f3venes han tenido la oportunidad de iniciar una reflexi\u00f3n sobre las posibles profesiones que podr\u00edan considerar, a trav\u00e9s de un test que destaca tambi\u00e9n sus afinidades. \u00a1Un gran primer paso hacia su futuro!<\/p>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-1 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"1080\" height=\"1080\" data-id=\"134079\" src=\"https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/11\/6.jpg\" alt=\"\" class=\"wp-image-134079\" srcset=\"https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/11\/6.jpg 1080w, https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/11\/6-250x250.jpg 250w, https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/11\/6-700x700.jpg 700w, https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/11\/6-150x150.jpg 150w, https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/11\/6-768x768.jpg 768w, https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/11\/6-120x120.jpg 120w\" sizes=\"auto, (max-width: 1080px) 100vw, 1080px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"1080\" height=\"1080\" data-id=\"134075\" src=\"https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/11\/5.jpg\" alt=\"\" class=\"wp-image-134075\" srcset=\"https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/11\/5.jpg 1080w, https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/11\/5-250x250.jpg 250w, https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/11\/5-700x700.jpg 700w, https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/11\/5-150x150.jpg 150w, https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/11\/5-768x768.jpg 768w, https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/11\/5-120x120.jpg 120w\" sizes=\"auto, (max-width: 1080px) 100vw, 1080px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"1080\" height=\"1080\" data-id=\"134071\" src=\"https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/11\/4.jpg\" alt=\"\" class=\"wp-image-134071\" srcset=\"https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/11\/4.jpg 1080w, https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/11\/4-250x250.jpg 250w, https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/11\/4-700x700.jpg 700w, https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/11\/4-150x150.jpg 150w, https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/11\/4-768x768.jpg 768w, https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/11\/4-120x120.jpg 120w\" sizes=\"auto, (max-width: 1080px) 100vw, 1080px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"1080\" height=\"1080\" data-id=\"134067\" src=\"https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/11\/3.jpg\" alt=\"\" class=\"wp-image-134067\" srcset=\"https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/11\/3.jpg 1080w, https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/11\/3-250x250.jpg 250w, https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/11\/3-700x700.jpg 700w, https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/11\/3-150x150.jpg 150w, https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/11\/3-768x768.jpg 768w, https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/11\/3-120x120.jpg 120w\" sizes=\"auto, (max-width: 1080px) 100vw, 1080px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"1080\" height=\"1080\" data-id=\"134063\" src=\"https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/11\/2.jpg\" alt=\"\" class=\"wp-image-134063\" srcset=\"https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/11\/2.jpg 1080w, https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/11\/2-250x250.jpg 250w, https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/11\/2-700x700.jpg 700w, https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/11\/2-150x150.jpg 150w, https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/11\/2-768x768.jpg 768w, https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/11\/2-120x120.jpg 120w\" sizes=\"auto, (max-width: 1080px) 100vw, 1080px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"1080\" height=\"1080\" data-id=\"134059\" src=\"https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/11\/1.jpg\" alt=\"\" class=\"wp-image-134059\" srcset=\"https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/11\/1.jpg 1080w, https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/11\/1-250x250.jpg 250w, https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/11\/1-700x700.jpg 700w, https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/11\/1-150x150.jpg 150w, https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/11\/1-768x768.jpg 768w, https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/11\/1-120x120.jpg 120w\" sizes=\"auto, (max-width: 1080px) 100vw, 1080px\" \/><\/figure>\n<\/figure>\n","protected":false},"excerpt":{"rendered":"Les \u00e9l\u00e8ves de 2nde ont particip\u00e9 \u00e0 leur premier atelier d\u2019orientation professionnelle \u00e0 \u00ab Barcelona Activa Porta 22 \u00bb ! ","protected":false},"author":1,"featured_media":134067,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"rs_blank_template":"","rs_page_bg_color":"","slide_template_v7":"","footnotes":"","_links_to":"","_links_to_target":""},"categories":[11,9],"tags":[],"class_list":["post-134058","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-2nde","category-secondaire"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Barcelona Activa Porta 22@ - Lyc\u00e9e International Barcelona \u00b7 Bon Soleil<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/bonsoleil.es\/es\/barcelona-activa-porta-22\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Barcelona Activa Porta 22@ - Lyc\u00e9e International Barcelona \u00b7 Bon Soleil\" \/>\n<meta property=\"og:description\" content=\"Les \u00e9l\u00e8ves de 2nde ont particip\u00e9 \u00e0 leur premier atelier d\u2019orientation professionnelle \u00e0 \u00ab Barcelona Activa Porta 22 \u00bb !\" \/>\n<meta property=\"og:url\" content=\"https:\/\/bonsoleil.es\/es\/barcelona-activa-porta-22\/\" \/>\n<meta property=\"og:site_name\" content=\"Lyc\u00e9e International Barcelona \u00b7 Bon Soleil\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/libBonSoleil\/\" \/>\n<meta property=\"article:published_time\" content=\"2024-10-22T07:18:43+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-11-13T08:26:16+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/11\/3.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1080\" \/>\n\t<meta property=\"og:image:height\" content=\"1080\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"libbs\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@lib_bonsoleil\" \/>\n<meta name=\"twitter:site\" content=\"@lib_bonsoleil\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"libbs\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/bonsoleil.es\\\/es\\\/barcelona-activa-porta-22\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/bonsoleil.es\\\/es\\\/barcelona-activa-porta-22\\\/\"},\"author\":{\"name\":\"libbs\",\"@id\":\"https:\\\/\\\/bonsoleil.es\\\/es\\\/#\\\/schema\\\/person\\\/f90f9175af4fad9c626fd2873bc546ec\"},\"headline\":\"Barcelona Activa Porta 22@\",\"datePublished\":\"2024-10-22T07:18:43+00:00\",\"dateModified\":\"2024-11-13T08:26:16+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/bonsoleil.es\\\/es\\\/barcelona-activa-porta-22\\\/\"},\"wordCount\":109,\"image\":{\"@id\":\"https:\\\/\\\/bonsoleil.es\\\/es\\\/barcelona-activa-porta-22\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/bonsoleil.es\\\/web\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/3.jpg\",\"articleSection\":[\"2nde\",\"Secondaire\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/bonsoleil.es\\\/es\\\/barcelona-activa-porta-22\\\/\",\"url\":\"https:\\\/\\\/bonsoleil.es\\\/es\\\/barcelona-activa-porta-22\\\/\",\"name\":\"Barcelona Activa Porta 22@ - Lyc\u00e9e International Barcelona \u00b7 Bon Soleil\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/bonsoleil.es\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/bonsoleil.es\\\/es\\\/barcelona-activa-porta-22\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/bonsoleil.es\\\/es\\\/barcelona-activa-porta-22\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/bonsoleil.es\\\/web\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/3.jpg\",\"datePublished\":\"2024-10-22T07:18:43+00:00\",\"dateModified\":\"2024-11-13T08:26:16+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/bonsoleil.es\\\/es\\\/#\\\/schema\\\/person\\\/f90f9175af4fad9c626fd2873bc546ec\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/bonsoleil.es\\\/es\\\/barcelona-activa-porta-22\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/bonsoleil.es\\\/es\\\/barcelona-activa-porta-22\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/bonsoleil.es\\\/es\\\/barcelona-activa-porta-22\\\/#primaryimage\",\"url\":\"https:\\\/\\\/bonsoleil.es\\\/web\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/3.jpg\",\"contentUrl\":\"https:\\\/\\\/bonsoleil.es\\\/web\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/3.jpg\",\"width\":1080,\"height\":1080},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/bonsoleil.es\\\/es\\\/barcelona-activa-porta-22\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/bonsoleil.es\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Barcelona Activa Porta 22@\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/bonsoleil.es\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/bonsoleil.es\\\/es\\\/\",\"name\":\"Lyc\u00e9e International Barcelona \u00b7 Bon Soleil\",\"description\":\"Lyc\u00e9e International Barcelona\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/bonsoleil.es\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/bonsoleil.es\\\/es\\\/#\\\/schema\\\/person\\\/f90f9175af4fad9c626fd2873bc546ec\",\"name\":\"libbs\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/bonsoleil.es\\\/web\\\/wp-content\\\/litespeed\\\/avatar\\\/6719caedb5831fa7538835120a8121f8.jpg?ver=1783691672\",\"url\":\"https:\\\/\\\/bonsoleil.es\\\/web\\\/wp-content\\\/litespeed\\\/avatar\\\/6719caedb5831fa7538835120a8121f8.jpg?ver=1783691672\",\"contentUrl\":\"https:\\\/\\\/bonsoleil.es\\\/web\\\/wp-content\\\/litespeed\\\/avatar\\\/6719caedb5831fa7538835120a8121f8.jpg?ver=1783691672\",\"caption\":\"libbs\"},\"sameAs\":[\"http:\\\/\\\/localhost\\\/bonsoleil\\\/new_web\"],\"url\":\"https:\\\/\\\/bonsoleil.es\\\/es\\\/author\\\/libbs\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Barcelona Activa Porta 22@ - Lyc\u00e9e International Barcelona \u00b7 Bon Soleil","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/bonsoleil.es\/es\/barcelona-activa-porta-22\/","og_locale":"es_ES","og_type":"article","og_title":"Barcelona Activa Porta 22@ - Lyc\u00e9e International Barcelona \u00b7 Bon Soleil","og_description":"Les \u00e9l\u00e8ves de 2nde ont particip\u00e9 \u00e0 leur premier atelier d\u2019orientation professionnelle \u00e0 \u00ab Barcelona Activa Porta 22 \u00bb !","og_url":"https:\/\/bonsoleil.es\/es\/barcelona-activa-porta-22\/","og_site_name":"Lyc\u00e9e International Barcelona \u00b7 Bon Soleil","article_publisher":"https:\/\/www.facebook.com\/libBonSoleil\/","article_published_time":"2024-10-22T07:18:43+00:00","article_modified_time":"2024-11-13T08:26:16+00:00","og_image":[{"width":1080,"height":1080,"url":"https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/11\/3.jpg","type":"image\/jpeg"}],"author":"libbs","twitter_card":"summary_large_image","twitter_creator":"@lib_bonsoleil","twitter_site":"@lib_bonsoleil","twitter_misc":{"Escrito por":"libbs","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/bonsoleil.es\/es\/barcelona-activa-porta-22\/#article","isPartOf":{"@id":"https:\/\/bonsoleil.es\/es\/barcelona-activa-porta-22\/"},"author":{"name":"libbs","@id":"https:\/\/bonsoleil.es\/es\/#\/schema\/person\/f90f9175af4fad9c626fd2873bc546ec"},"headline":"Barcelona Activa Porta 22@","datePublished":"2024-10-22T07:18:43+00:00","dateModified":"2024-11-13T08:26:16+00:00","mainEntityOfPage":{"@id":"https:\/\/bonsoleil.es\/es\/barcelona-activa-porta-22\/"},"wordCount":109,"image":{"@id":"https:\/\/bonsoleil.es\/es\/barcelona-activa-porta-22\/#primaryimage"},"thumbnailUrl":"https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/11\/3.jpg","articleSection":["2nde","Secondaire"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/bonsoleil.es\/es\/barcelona-activa-porta-22\/","url":"https:\/\/bonsoleil.es\/es\/barcelona-activa-porta-22\/","name":"Barcelona Activa Porta 22@ - Lyc\u00e9e International Barcelona \u00b7 Bon Soleil","isPartOf":{"@id":"https:\/\/bonsoleil.es\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/bonsoleil.es\/es\/barcelona-activa-porta-22\/#primaryimage"},"image":{"@id":"https:\/\/bonsoleil.es\/es\/barcelona-activa-porta-22\/#primaryimage"},"thumbnailUrl":"https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/11\/3.jpg","datePublished":"2024-10-22T07:18:43+00:00","dateModified":"2024-11-13T08:26:16+00:00","author":{"@id":"https:\/\/bonsoleil.es\/es\/#\/schema\/person\/f90f9175af4fad9c626fd2873bc546ec"},"breadcrumb":{"@id":"https:\/\/bonsoleil.es\/es\/barcelona-activa-porta-22\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/bonsoleil.es\/es\/barcelona-activa-porta-22\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/bonsoleil.es\/es\/barcelona-activa-porta-22\/#primaryimage","url":"https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/11\/3.jpg","contentUrl":"https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/11\/3.jpg","width":1080,"height":1080},{"@type":"BreadcrumbList","@id":"https:\/\/bonsoleil.es\/es\/barcelona-activa-porta-22\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/bonsoleil.es\/es\/"},{"@type":"ListItem","position":2,"name":"Barcelona Activa Porta 22@"}]},{"@type":"WebSite","@id":"https:\/\/bonsoleil.es\/es\/#website","url":"https:\/\/bonsoleil.es\/es\/","name":"Lyc\u00e9e International Barcelona \u00b7 Bon Soleil","description":"Lyc\u00e9e International Barcelona","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/bonsoleil.es\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/bonsoleil.es\/es\/#\/schema\/person\/f90f9175af4fad9c626fd2873bc546ec","name":"libbs","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/bonsoleil.es\/web\/wp-content\/litespeed\/avatar\/6719caedb5831fa7538835120a8121f8.jpg?ver=1783691672","url":"https:\/\/bonsoleil.es\/web\/wp-content\/litespeed\/avatar\/6719caedb5831fa7538835120a8121f8.jpg?ver=1783691672","contentUrl":"https:\/\/bonsoleil.es\/web\/wp-content\/litespeed\/avatar\/6719caedb5831fa7538835120a8121f8.jpg?ver=1783691672","caption":"libbs"},"sameAs":["http:\/\/localhost\/bonsoleil\/new_web"],"url":"https:\/\/bonsoleil.es\/es\/author\/libbs\/"}]}},"_links":{"self":[{"href":"https:\/\/bonsoleil.es\/es\/wp-json\/wp\/v2\/posts\/134058","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/bonsoleil.es\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/bonsoleil.es\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/bonsoleil.es\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/bonsoleil.es\/es\/wp-json\/wp\/v2\/comments?post=134058"}],"version-history":[{"count":2,"href":"https:\/\/bonsoleil.es\/es\/wp-json\/wp\/v2\/posts\/134058\/revisions"}],"predecessor-version":[{"id":134130,"href":"https:\/\/bonsoleil.es\/es\/wp-json\/wp\/v2\/posts\/134058\/revisions\/134130"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/bonsoleil.es\/es\/wp-json\/wp\/v2\/media\/134067"}],"wp:attachment":[{"href":"https:\/\/bonsoleil.es\/es\/wp-json\/wp\/v2\/media?parent=134058"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/bonsoleil.es\/es\/wp-json\/wp\/v2\/categories?post=134058"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/bonsoleil.es\/es\/wp-json\/wp\/v2\/tags?post=134058"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}