{"id":134897,"date":"2024-12-09T16:12:18","date_gmt":"2024-12-09T15:12:18","guid":{"rendered":"https:\/\/bonsoleil.es\/?p=134897"},"modified":"2024-12-09T16:12:20","modified_gmt":"2024-12-09T15:12:20","slug":"our-families","status":"publish","type":"post","link":"https:\/\/bonsoleil.es\/es\/our-families\/","title":{"rendered":"Our families"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">The children in CP brought photos of their families to class to share with their classmates. They answered questions like \u00abWho is this?\u00bb and \u00abWhere are you in this photo?\u00bb as they showed their pictures. The activity gave them a chance to practice speaking English while talking about their loved ones. The kids were very excited to share these personal moments with their friends. It was a fun way to get them talking in class.<br>\u2026<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Les \u00e9l\u00e8ves de CP ont apport\u00e9 des photos de leurs familles en classe pour les partager avec leurs camarades. En montrant leurs images, ils ont r\u00e9pondu \u00e0 des questions telles que \u00ab Qui est-ce ? \u00bb et \u00ab O\u00f9 es-tu sur cette photo ? \u00bb. Cette activit\u00e9 leur a permis de pratiquer l&#8217;anglais tout en parlant de leurs proches. Les enfants \u00e9taient tr\u00e8s enthousiastes \u00e0 l&#8217;id\u00e9e de partager ces moments personnels avec leurs amis. C&#8217;\u00e9tait une mani\u00e8re ludique de les inciter \u00e0 s&#8217;exprimer en classe.<\/p>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-2 is-cropped wp-block-gallery-1 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"700\" height=\"700\" data-id=\"134902\" src=\"https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/12\/1-2-700x700.jpg\" alt=\"\" class=\"wp-image-134902\" srcset=\"https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/12\/1-2-700x700.jpg 700w, https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/12\/1-2-250x250.jpg 250w, https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/12\/1-2-150x150.jpg 150w, https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/12\/1-2-768x768.jpg 768w, https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/12\/1-2-120x120.jpg 120w, https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/12\/1-2.jpg 1080w\" sizes=\"auto, (max-width: 700px) 100vw, 700px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"700\" height=\"700\" data-id=\"134914\" src=\"https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/12\/4-1-700x700.jpg\" alt=\"\" class=\"wp-image-134914\" srcset=\"https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/12\/4-1-700x700.jpg 700w, https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/12\/4-1-250x250.jpg 250w, https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/12\/4-1-150x150.jpg 150w, https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/12\/4-1-768x768.jpg 768w, https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/12\/4-1-120x120.jpg 120w, https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/12\/4-1.jpg 1080w\" sizes=\"auto, (max-width: 700px) 100vw, 700px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"700\" height=\"700\" data-id=\"134906\" src=\"https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/12\/2-1-700x700.jpg\" alt=\"\" class=\"wp-image-134906\" srcset=\"https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/12\/2-1-700x700.jpg 700w, https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/12\/2-1-250x250.jpg 250w, https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/12\/2-1-150x150.jpg 150w, https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/12\/2-1-768x768.jpg 768w, https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/12\/2-1-120x120.jpg 120w, https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/12\/2-1.jpg 1080w\" sizes=\"auto, (max-width: 700px) 100vw, 700px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"700\" height=\"700\" data-id=\"134910\" src=\"https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/12\/3-1-700x700.jpg\" alt=\"\" class=\"wp-image-134910\" srcset=\"https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/12\/3-1-700x700.jpg 700w, https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/12\/3-1-250x250.jpg 250w, https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/12\/3-1-150x150.jpg 150w, https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/12\/3-1-768x768.jpg 768w, https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/12\/3-1-120x120.jpg 120w, https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/12\/3-1.jpg 1080w\" sizes=\"auto, (max-width: 700px) 100vw, 700px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"700\" height=\"700\" data-id=\"134898\" src=\"https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/12\/5-1-700x700.jpg\" alt=\"\" class=\"wp-image-134898\" srcset=\"https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/12\/5-1-700x700.jpg 700w, https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/12\/5-1-250x250.jpg 250w, https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/12\/5-1-150x150.jpg 150w, https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/12\/5-1-768x768.jpg 768w, https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/12\/5-1-120x120.jpg 120w, https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/12\/5-1.jpg 1080w\" sizes=\"auto, (max-width: 700px) 100vw, 700px\" \/><\/figure>\n<\/figure>\n","protected":false},"excerpt":{"rendered":"The children in CP brought photos of their families to class to share with their classmates. They answered questions like \u00abWho is this?\u00bb and \u00abWhere are you in this photo?\u00bb ","protected":false},"author":1,"featured_media":134902,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"rs_blank_template":"","rs_page_bg_color":"","slide_template_v7":"","footnotes":"","_links_to":"","_links_to_target":""},"categories":[21,14],"tags":[],"class_list":["post-134897","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cp","category-primaire"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Our families - Lyc\u00e9e International Barcelona \u00b7 Bon Soleil<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/bonsoleil.es\/es\/our-families\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Our families - Lyc\u00e9e International Barcelona \u00b7 Bon Soleil\" \/>\n<meta property=\"og:description\" content=\"The children in CP brought photos of their families to class to share with their classmates. They answered questions like &quot;Who is this?&quot; and &quot;Where are you in this photo?&quot;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/bonsoleil.es\/es\/our-families\/\" \/>\n<meta property=\"og:site_name\" content=\"Lyc\u00e9e International Barcelona \u00b7 Bon Soleil\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/libBonSoleil\/\" \/>\n<meta property=\"article:published_time\" content=\"2024-12-09T15:12:18+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-12-09T15:12:20+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/12\/1-2.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1080\" \/>\n\t<meta property=\"og:image:height\" content=\"1080\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"libbs\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@lib_bonsoleil\" \/>\n<meta name=\"twitter:site\" content=\"@lib_bonsoleil\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"libbs\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/bonsoleil.es\\\/es\\\/our-families\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/bonsoleil.es\\\/es\\\/our-families\\\/\"},\"author\":{\"name\":\"libbs\",\"@id\":\"https:\\\/\\\/bonsoleil.es\\\/es\\\/#\\\/schema\\\/person\\\/f90f9175af4fad9c626fd2873bc546ec\"},\"headline\":\"Our families\",\"datePublished\":\"2024-12-09T15:12:18+00:00\",\"dateModified\":\"2024-12-09T15:12:20+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/bonsoleil.es\\\/es\\\/our-families\\\/\"},\"wordCount\":162,\"image\":{\"@id\":\"https:\\\/\\\/bonsoleil.es\\\/es\\\/our-families\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/bonsoleil.es\\\/web\\\/wp-content\\\/uploads\\\/2024\\\/12\\\/1-2.jpg\",\"articleSection\":[\"CP\",\"Primaire\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/bonsoleil.es\\\/es\\\/our-families\\\/\",\"url\":\"https:\\\/\\\/bonsoleil.es\\\/es\\\/our-families\\\/\",\"name\":\"Our families - Lyc\u00e9e International Barcelona \u00b7 Bon Soleil\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/bonsoleil.es\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/bonsoleil.es\\\/es\\\/our-families\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/bonsoleil.es\\\/es\\\/our-families\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/bonsoleil.es\\\/web\\\/wp-content\\\/uploads\\\/2024\\\/12\\\/1-2.jpg\",\"datePublished\":\"2024-12-09T15:12:18+00:00\",\"dateModified\":\"2024-12-09T15:12:20+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/bonsoleil.es\\\/es\\\/#\\\/schema\\\/person\\\/f90f9175af4fad9c626fd2873bc546ec\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/bonsoleil.es\\\/es\\\/our-families\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/bonsoleil.es\\\/es\\\/our-families\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/bonsoleil.es\\\/es\\\/our-families\\\/#primaryimage\",\"url\":\"https:\\\/\\\/bonsoleil.es\\\/web\\\/wp-content\\\/uploads\\\/2024\\\/12\\\/1-2.jpg\",\"contentUrl\":\"https:\\\/\\\/bonsoleil.es\\\/web\\\/wp-content\\\/uploads\\\/2024\\\/12\\\/1-2.jpg\",\"width\":1080,\"height\":1080},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/bonsoleil.es\\\/es\\\/our-families\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/bonsoleil.es\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Our families\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/bonsoleil.es\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/bonsoleil.es\\\/es\\\/\",\"name\":\"Lyc\u00e9e International Barcelona \u00b7 Bon Soleil\",\"description\":\"Lyc\u00e9e International Barcelona\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/bonsoleil.es\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/bonsoleil.es\\\/es\\\/#\\\/schema\\\/person\\\/f90f9175af4fad9c626fd2873bc546ec\",\"name\":\"libbs\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/bonsoleil.es\\\/web\\\/wp-content\\\/litespeed\\\/avatar\\\/6719caedb5831fa7538835120a8121f8.jpg?ver=1783691672\",\"url\":\"https:\\\/\\\/bonsoleil.es\\\/web\\\/wp-content\\\/litespeed\\\/avatar\\\/6719caedb5831fa7538835120a8121f8.jpg?ver=1783691672\",\"contentUrl\":\"https:\\\/\\\/bonsoleil.es\\\/web\\\/wp-content\\\/litespeed\\\/avatar\\\/6719caedb5831fa7538835120a8121f8.jpg?ver=1783691672\",\"caption\":\"libbs\"},\"sameAs\":[\"http:\\\/\\\/localhost\\\/bonsoleil\\\/new_web\"],\"url\":\"https:\\\/\\\/bonsoleil.es\\\/es\\\/author\\\/libbs\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Our families - Lyc\u00e9e International Barcelona \u00b7 Bon Soleil","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/bonsoleil.es\/es\/our-families\/","og_locale":"es_ES","og_type":"article","og_title":"Our families - Lyc\u00e9e International Barcelona \u00b7 Bon Soleil","og_description":"The children in CP brought photos of their families to class to share with their classmates. They answered questions like \"Who is this?\" and \"Where are you in this photo?\"","og_url":"https:\/\/bonsoleil.es\/es\/our-families\/","og_site_name":"Lyc\u00e9e International Barcelona \u00b7 Bon Soleil","article_publisher":"https:\/\/www.facebook.com\/libBonSoleil\/","article_published_time":"2024-12-09T15:12:18+00:00","article_modified_time":"2024-12-09T15:12:20+00:00","og_image":[{"width":1080,"height":1080,"url":"https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/12\/1-2.jpg","type":"image\/jpeg"}],"author":"libbs","twitter_card":"summary_large_image","twitter_creator":"@lib_bonsoleil","twitter_site":"@lib_bonsoleil","twitter_misc":{"Escrito por":"libbs","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/bonsoleil.es\/es\/our-families\/#article","isPartOf":{"@id":"https:\/\/bonsoleil.es\/es\/our-families\/"},"author":{"name":"libbs","@id":"https:\/\/bonsoleil.es\/es\/#\/schema\/person\/f90f9175af4fad9c626fd2873bc546ec"},"headline":"Our families","datePublished":"2024-12-09T15:12:18+00:00","dateModified":"2024-12-09T15:12:20+00:00","mainEntityOfPage":{"@id":"https:\/\/bonsoleil.es\/es\/our-families\/"},"wordCount":162,"image":{"@id":"https:\/\/bonsoleil.es\/es\/our-families\/#primaryimage"},"thumbnailUrl":"https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/12\/1-2.jpg","articleSection":["CP","Primaire"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/bonsoleil.es\/es\/our-families\/","url":"https:\/\/bonsoleil.es\/es\/our-families\/","name":"Our families - Lyc\u00e9e International Barcelona \u00b7 Bon Soleil","isPartOf":{"@id":"https:\/\/bonsoleil.es\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/bonsoleil.es\/es\/our-families\/#primaryimage"},"image":{"@id":"https:\/\/bonsoleil.es\/es\/our-families\/#primaryimage"},"thumbnailUrl":"https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/12\/1-2.jpg","datePublished":"2024-12-09T15:12:18+00:00","dateModified":"2024-12-09T15:12:20+00:00","author":{"@id":"https:\/\/bonsoleil.es\/es\/#\/schema\/person\/f90f9175af4fad9c626fd2873bc546ec"},"breadcrumb":{"@id":"https:\/\/bonsoleil.es\/es\/our-families\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/bonsoleil.es\/es\/our-families\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/bonsoleil.es\/es\/our-families\/#primaryimage","url":"https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/12\/1-2.jpg","contentUrl":"https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2024\/12\/1-2.jpg","width":1080,"height":1080},{"@type":"BreadcrumbList","@id":"https:\/\/bonsoleil.es\/es\/our-families\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/bonsoleil.es\/es\/"},{"@type":"ListItem","position":2,"name":"Our families"}]},{"@type":"WebSite","@id":"https:\/\/bonsoleil.es\/es\/#website","url":"https:\/\/bonsoleil.es\/es\/","name":"Lyc\u00e9e International Barcelona \u00b7 Bon Soleil","description":"Lyc\u00e9e International Barcelona","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/bonsoleil.es\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/bonsoleil.es\/es\/#\/schema\/person\/f90f9175af4fad9c626fd2873bc546ec","name":"libbs","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/bonsoleil.es\/web\/wp-content\/litespeed\/avatar\/6719caedb5831fa7538835120a8121f8.jpg?ver=1783691672","url":"https:\/\/bonsoleil.es\/web\/wp-content\/litespeed\/avatar\/6719caedb5831fa7538835120a8121f8.jpg?ver=1783691672","contentUrl":"https:\/\/bonsoleil.es\/web\/wp-content\/litespeed\/avatar\/6719caedb5831fa7538835120a8121f8.jpg?ver=1783691672","caption":"libbs"},"sameAs":["http:\/\/localhost\/bonsoleil\/new_web"],"url":"https:\/\/bonsoleil.es\/es\/author\/libbs\/"}]}},"_links":{"self":[{"href":"https:\/\/bonsoleil.es\/es\/wp-json\/wp\/v2\/posts\/134897","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/bonsoleil.es\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/bonsoleil.es\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/bonsoleil.es\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/bonsoleil.es\/es\/wp-json\/wp\/v2\/comments?post=134897"}],"version-history":[{"count":1,"href":"https:\/\/bonsoleil.es\/es\/wp-json\/wp\/v2\/posts\/134897\/revisions"}],"predecessor-version":[{"id":134918,"href":"https:\/\/bonsoleil.es\/es\/wp-json\/wp\/v2\/posts\/134897\/revisions\/134918"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/bonsoleil.es\/es\/wp-json\/wp\/v2\/media\/134902"}],"wp:attachment":[{"href":"https:\/\/bonsoleil.es\/es\/wp-json\/wp\/v2\/media?parent=134897"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/bonsoleil.es\/es\/wp-json\/wp\/v2\/categories?post=134897"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/bonsoleil.es\/es\/wp-json\/wp\/v2\/tags?post=134897"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}