{"id":64253,"date":"2022-11-04T09:09:10","date_gmt":"2022-11-04T08:09:10","guid":{"rendered":"https:\/\/www.bonsoleil.es\/?p=64253"},"modified":"2022-11-04T09:09:10","modified_gmt":"2022-11-04T08:09:10","slug":"la-girafe","status":"publish","type":"post","link":"https:\/\/bonsoleil.es\/es\/la-girafe\/","title":{"rendered":"La girafe"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">En d\u00e9but de p\u00e9riode, nous avons choisi chacun un animal et nous l&#8217;avons \u00e9crit sur un bout de papier. Ensuite, nous avons tir\u00e9 au sort l&#8217;animal que nous \u00e9tudierions et c&#8217;est la <strong>girafe<\/strong> qui a \u00e9t\u00e9 choisie !&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La ma\u00eetresse a regroup\u00e9 des ressources en lien avec la girafe (livres, peluches, objets, animaux de la savane,..) afin de cr\u00e9er un mini-monde, un <strong>coin sensoriel et \u00e9ducatif<\/strong> sur le th\u00e8me de la girafe.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Pour compl\u00e9ter notre \u00abcoin girafe\u00bb, la maman de Miguel a eu l&#8217;\u00e9norme gentillesse de nous apporter d&#8217;extraordinaires <strong>\u00e9l\u00e9ments r\u00e9els<\/strong> sur la girafe : un <strong>morceau de peau, des sabots, une dent, une vert\u00e8bre cervicale, un poil de la queue<\/strong>, des masques \u00e0 colorier, des images, &#8230; Nous avons \u00e9t\u00e9 tr\u00e8s g\u00e2t\u00e9s et nous la remercions \u00e9norm\u00e9ment pour le temps qu&#8217;elle a pris \u00e0 nous pr\u00e9parer ces magnifiques tr\u00e9sors ! Gr\u00e2ce \u00e0 cela, nous avons pu <strong>analyser<\/strong> et <strong>observer<\/strong> de tr\u00e8s pr\u00e8s certaines <strong>caract\u00e9ristiques physiques<\/strong> de la girafe. Nous avons fait appel \u00e0 nos sens : l&#8217;odorat, la vue et le toucher que nous avons utilis\u00e9s pour exploiter et d\u00e9couvrir. Cela nous a apport\u00e9 des r\u00e9ponses \u00e0 toutes nos questions.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-1 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-full\"><a href=\"https:\/\/www.bonsoleil.es\/bonsoleil\/wp-content\/uploads\/2022\/11\/IMG_8976-scaled.jpg\"><img decoding=\"async\" data-id=\"64255\" src=\"https:\/\/www.bonsoleil.es\/bonsoleil\/wp-content\/uploads\/2022\/11\/IMG_8976-scaled.jpg\" alt=\"\" class=\"wp-image-64255\"\/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-full\"><a href=\"https:\/\/www.bonsoleil.es\/bonsoleil\/wp-content\/uploads\/2022\/11\/IMG_8960-2-scaled.jpg\"><img decoding=\"async\" data-id=\"64254\" src=\"https:\/\/www.bonsoleil.es\/bonsoleil\/wp-content\/uploads\/2022\/11\/IMG_8960-2-scaled.jpg\" alt=\"\" class=\"wp-image-64254\"\/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-full\"><a href=\"https:\/\/www.bonsoleil.es\/bonsoleil\/wp-content\/uploads\/2022\/11\/IMG_8988-scaled.jpg\"><img decoding=\"async\" data-id=\"64257\" src=\"https:\/\/www.bonsoleil.es\/bonsoleil\/wp-content\/uploads\/2022\/11\/IMG_8988-scaled.jpg\" alt=\"\" class=\"wp-image-64257\"\/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-full\"><a href=\"https:\/\/www.bonsoleil.es\/bonsoleil\/wp-content\/uploads\/2022\/11\/IMG_8993-scaled.jpg\"><img decoding=\"async\" data-id=\"64259\" src=\"https:\/\/www.bonsoleil.es\/bonsoleil\/wp-content\/uploads\/2022\/11\/IMG_8993-scaled.jpg\" alt=\"\" class=\"wp-image-64259\"\/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-full\"><a href=\"https:\/\/www.bonsoleil.es\/bonsoleil\/wp-content\/uploads\/2022\/11\/IMG_8980-scaled.jpg\"><img decoding=\"async\" data-id=\"64256\" src=\"https:\/\/www.bonsoleil.es\/bonsoleil\/wp-content\/uploads\/2022\/11\/IMG_8980-scaled.jpg\" alt=\"\" class=\"wp-image-64256\"\/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-full\"><a href=\"https:\/\/www.bonsoleil.es\/bonsoleil\/wp-content\/uploads\/2022\/11\/IMG_8995-scaled.jpg\"><img decoding=\"async\" data-id=\"64260\" src=\"https:\/\/www.bonsoleil.es\/bonsoleil\/wp-content\/uploads\/2022\/11\/IMG_8995-scaled.jpg\" alt=\"\" class=\"wp-image-64260\"\/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-full\"><a href=\"https:\/\/www.bonsoleil.es\/bonsoleil\/wp-content\/uploads\/2022\/11\/IMG_9025-scaled.jpg\"><img decoding=\"async\" data-id=\"64261\" src=\"https:\/\/www.bonsoleil.es\/bonsoleil\/wp-content\/uploads\/2022\/11\/IMG_9025-scaled.jpg\" alt=\"\" class=\"wp-image-64261\"\/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-full\"><a href=\"https:\/\/www.bonsoleil.es\/bonsoleil\/wp-content\/uploads\/2022\/11\/IMG_8992-scaled.jpg\"><img decoding=\"async\" data-id=\"64258\" src=\"https:\/\/www.bonsoleil.es\/bonsoleil\/wp-content\/uploads\/2022\/11\/IMG_8992-scaled.jpg\" alt=\"\" class=\"wp-image-64258\"\/><\/a><\/figure>\n<\/figure>\n","protected":false},"excerpt":{"rendered":"En d\u00e9but de p\u00e9riode, nous avons choisi chacun un animal et nous l&#8217;avons \u00e9crit sur un bout de papier. Ensuite, nous avons tir\u00e9 au sort l&#8217;animal que nous \u00e9tudierions et c&#8217;est la girafe qui a \u00e9t\u00e9 choisie !\u00a0","protected":false},"author":1,"featured_media":64255,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"rs_blank_template":"","rs_page_bg_color":"","slide_template_v7":"","footnotes":"","_links_to":"","_links_to_target":""},"categories":[22,14],"tags":[],"class_list":["post-64253","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-gs","category-primaire"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>La girafe - Lyc\u00e9e International Barcelona \u00b7 Bon Soleil<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/bonsoleil.es\/es\/la-girafe\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La girafe - Lyc\u00e9e International Barcelona \u00b7 Bon Soleil\" \/>\n<meta property=\"og:description\" content=\"En d\u00e9but de p\u00e9riode, nous avons choisi chacun un animal et nous l&#039;avons \u00e9crit sur un bout de papier. Ensuite, nous avons tir\u00e9 au sort l&#039;animal que nous \u00e9tudierions et c&#039;est la girafe qui a \u00e9t\u00e9 choisie !\u00a0\" \/>\n<meta property=\"og:url\" content=\"https:\/\/bonsoleil.es\/es\/la-girafe\/\" \/>\n<meta property=\"og:site_name\" content=\"Lyc\u00e9e International Barcelona \u00b7 Bon Soleil\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/libBonSoleil\/\" \/>\n<meta property=\"article:published_time\" content=\"2022-11-04T08:09:10+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2022\/11\/IMG_8976-scaled-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1920\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"libbs\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@lib_bonsoleil\" \/>\n<meta name=\"twitter:site\" content=\"@lib_bonsoleil\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"libbs\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/bonsoleil.es\\\/es\\\/la-girafe\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/bonsoleil.es\\\/es\\\/la-girafe\\\/\"},\"author\":{\"name\":\"libbs\",\"@id\":\"https:\\\/\\\/bonsoleil.es\\\/es\\\/#\\\/schema\\\/person\\\/f90f9175af4fad9c626fd2873bc546ec\"},\"headline\":\"La girafe\",\"datePublished\":\"2022-11-04T08:09:10+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/bonsoleil.es\\\/es\\\/la-girafe\\\/\"},\"wordCount\":215,\"image\":{\"@id\":\"https:\\\/\\\/bonsoleil.es\\\/es\\\/la-girafe\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/bonsoleil.es\\\/web\\\/wp-content\\\/uploads\\\/2022\\\/11\\\/IMG_8976-scaled-1.jpg\",\"articleSection\":[\"GS\",\"Primaire\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/bonsoleil.es\\\/es\\\/la-girafe\\\/\",\"url\":\"https:\\\/\\\/bonsoleil.es\\\/es\\\/la-girafe\\\/\",\"name\":\"La girafe - Lyc\u00e9e International Barcelona \u00b7 Bon Soleil\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/bonsoleil.es\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/bonsoleil.es\\\/es\\\/la-girafe\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/bonsoleil.es\\\/es\\\/la-girafe\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/bonsoleil.es\\\/web\\\/wp-content\\\/uploads\\\/2022\\\/11\\\/IMG_8976-scaled-1.jpg\",\"datePublished\":\"2022-11-04T08:09:10+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/bonsoleil.es\\\/es\\\/#\\\/schema\\\/person\\\/f90f9175af4fad9c626fd2873bc546ec\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/bonsoleil.es\\\/es\\\/la-girafe\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/bonsoleil.es\\\/es\\\/la-girafe\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/bonsoleil.es\\\/es\\\/la-girafe\\\/#primaryimage\",\"url\":\"https:\\\/\\\/bonsoleil.es\\\/web\\\/wp-content\\\/uploads\\\/2022\\\/11\\\/IMG_8976-scaled-1.jpg\",\"contentUrl\":\"https:\\\/\\\/bonsoleil.es\\\/web\\\/wp-content\\\/uploads\\\/2022\\\/11\\\/IMG_8976-scaled-1.jpg\",\"width\":2560,\"height\":1920},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/bonsoleil.es\\\/es\\\/la-girafe\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/bonsoleil.es\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"La girafe\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/bonsoleil.es\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/bonsoleil.es\\\/es\\\/\",\"name\":\"Lyc\u00e9e International Barcelona \u00b7 Bon Soleil\",\"description\":\"Lyc\u00e9e International Barcelona\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/bonsoleil.es\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/bonsoleil.es\\\/es\\\/#\\\/schema\\\/person\\\/f90f9175af4fad9c626fd2873bc546ec\",\"name\":\"libbs\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/bonsoleil.es\\\/web\\\/wp-content\\\/litespeed\\\/avatar\\\/6719caedb5831fa7538835120a8121f8.jpg?ver=1787925917\",\"url\":\"https:\\\/\\\/bonsoleil.es\\\/web\\\/wp-content\\\/litespeed\\\/avatar\\\/6719caedb5831fa7538835120a8121f8.jpg?ver=1787925917\",\"contentUrl\":\"https:\\\/\\\/bonsoleil.es\\\/web\\\/wp-content\\\/litespeed\\\/avatar\\\/6719caedb5831fa7538835120a8121f8.jpg?ver=1787925917\",\"caption\":\"libbs\"},\"sameAs\":[\"http:\\\/\\\/localhost\\\/bonsoleil\\\/new_web\"],\"url\":\"https:\\\/\\\/bonsoleil.es\\\/es\\\/author\\\/libbs\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"La girafe - Lyc\u00e9e International Barcelona \u00b7 Bon Soleil","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/bonsoleil.es\/es\/la-girafe\/","og_locale":"es_ES","og_type":"article","og_title":"La girafe - Lyc\u00e9e International Barcelona \u00b7 Bon Soleil","og_description":"En d\u00e9but de p\u00e9riode, nous avons choisi chacun un animal et nous l'avons \u00e9crit sur un bout de papier. Ensuite, nous avons tir\u00e9 au sort l'animal que nous \u00e9tudierions et c'est la girafe qui a \u00e9t\u00e9 choisie !\u00a0","og_url":"https:\/\/bonsoleil.es\/es\/la-girafe\/","og_site_name":"Lyc\u00e9e International Barcelona \u00b7 Bon Soleil","article_publisher":"https:\/\/www.facebook.com\/libBonSoleil\/","article_published_time":"2022-11-04T08:09:10+00:00","og_image":[{"width":2560,"height":1920,"url":"https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2022\/11\/IMG_8976-scaled-1.jpg","type":"image\/jpeg"}],"author":"libbs","twitter_card":"summary_large_image","twitter_creator":"@lib_bonsoleil","twitter_site":"@lib_bonsoleil","twitter_misc":{"Escrito por":"libbs","Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/bonsoleil.es\/es\/la-girafe\/#article","isPartOf":{"@id":"https:\/\/bonsoleil.es\/es\/la-girafe\/"},"author":{"name":"libbs","@id":"https:\/\/bonsoleil.es\/es\/#\/schema\/person\/f90f9175af4fad9c626fd2873bc546ec"},"headline":"La girafe","datePublished":"2022-11-04T08:09:10+00:00","mainEntityOfPage":{"@id":"https:\/\/bonsoleil.es\/es\/la-girafe\/"},"wordCount":215,"image":{"@id":"https:\/\/bonsoleil.es\/es\/la-girafe\/#primaryimage"},"thumbnailUrl":"https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2022\/11\/IMG_8976-scaled-1.jpg","articleSection":["GS","Primaire"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/bonsoleil.es\/es\/la-girafe\/","url":"https:\/\/bonsoleil.es\/es\/la-girafe\/","name":"La girafe - Lyc\u00e9e International Barcelona \u00b7 Bon Soleil","isPartOf":{"@id":"https:\/\/bonsoleil.es\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/bonsoleil.es\/es\/la-girafe\/#primaryimage"},"image":{"@id":"https:\/\/bonsoleil.es\/es\/la-girafe\/#primaryimage"},"thumbnailUrl":"https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2022\/11\/IMG_8976-scaled-1.jpg","datePublished":"2022-11-04T08:09:10+00:00","author":{"@id":"https:\/\/bonsoleil.es\/es\/#\/schema\/person\/f90f9175af4fad9c626fd2873bc546ec"},"breadcrumb":{"@id":"https:\/\/bonsoleil.es\/es\/la-girafe\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/bonsoleil.es\/es\/la-girafe\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/bonsoleil.es\/es\/la-girafe\/#primaryimage","url":"https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2022\/11\/IMG_8976-scaled-1.jpg","contentUrl":"https:\/\/bonsoleil.es\/web\/wp-content\/uploads\/2022\/11\/IMG_8976-scaled-1.jpg","width":2560,"height":1920},{"@type":"BreadcrumbList","@id":"https:\/\/bonsoleil.es\/es\/la-girafe\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/bonsoleil.es\/es\/"},{"@type":"ListItem","position":2,"name":"La girafe"}]},{"@type":"WebSite","@id":"https:\/\/bonsoleil.es\/es\/#website","url":"https:\/\/bonsoleil.es\/es\/","name":"Lyc\u00e9e International Barcelona \u00b7 Bon Soleil","description":"Lyc\u00e9e International Barcelona","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/bonsoleil.es\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/bonsoleil.es\/es\/#\/schema\/person\/f90f9175af4fad9c626fd2873bc546ec","name":"libbs","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/bonsoleil.es\/web\/wp-content\/litespeed\/avatar\/6719caedb5831fa7538835120a8121f8.jpg?ver=1787925917","url":"https:\/\/bonsoleil.es\/web\/wp-content\/litespeed\/avatar\/6719caedb5831fa7538835120a8121f8.jpg?ver=1787925917","contentUrl":"https:\/\/bonsoleil.es\/web\/wp-content\/litespeed\/avatar\/6719caedb5831fa7538835120a8121f8.jpg?ver=1787925917","caption":"libbs"},"sameAs":["http:\/\/localhost\/bonsoleil\/new_web"],"url":"https:\/\/bonsoleil.es\/es\/author\/libbs\/"}]}},"_links":{"self":[{"href":"https:\/\/bonsoleil.es\/es\/wp-json\/wp\/v2\/posts\/64253","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/bonsoleil.es\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/bonsoleil.es\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/bonsoleil.es\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/bonsoleil.es\/es\/wp-json\/wp\/v2\/comments?post=64253"}],"version-history":[{"count":0,"href":"https:\/\/bonsoleil.es\/es\/wp-json\/wp\/v2\/posts\/64253\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/bonsoleil.es\/es\/wp-json\/wp\/v2\/media\/64255"}],"wp:attachment":[{"href":"https:\/\/bonsoleil.es\/es\/wp-json\/wp\/v2\/media?parent=64253"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/bonsoleil.es\/es\/wp-json\/wp\/v2\/categories?post=64253"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/bonsoleil.es\/es\/wp-json\/wp\/v2\/tags?post=64253"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}